{"id":15204,"date":"2023-03-10T11:10:00","date_gmt":"2023-03-10T14:10:00","guid":{"rendered":"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/?page_id=15204"},"modified":"2026-03-18T11:22:12","modified_gmt":"2026-03-18T14:22:12","slug":"restaurantes","status":"publish","type":"page","link":"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/restaurantes\/","title":{"rendered":"Restaurantes"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"15204\" class=\"elementor elementor-15204\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3869a97 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3869a97\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ff2b862\" data-id=\"ff2b862\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f173aed elementor-widget elementor-widget-heading\" data-id=\"f173aed\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-xl\">RESTAURANTES<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-49d3cad elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"49d3cad\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-760dcf2\" data-id=\"760dcf2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15e76a5 elementor-widget elementor-widget-spacer\" data-id=\"15e76a5\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c89321f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c89321f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-5c77f6d\" data-id=\"5c77f6d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ad20b6 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"8ad20b6\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/9c90edd3-ce6e-40ac-91eb-8609d2b889d1-768x432.jpg\" alt=\"9c90edd3-ce6e-40ac-91eb-8609d2b889d1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/3886170a-4844-4a36-b529-5cdd61a6f2de-768x432.jpg\" alt=\"3886170a-4844-4a36-b529-5cdd61a6f2de\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/d64d7e34-9cc8-48f7-90f6-0b6f3259504d-768x432.jpg\" alt=\"d64d7e34-9cc8-48f7-90f6-0b6f3259504d\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a35e66e elementor-widget elementor-widget-heading\" data-id=\"a35e66e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Antisa & Roketa\n<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-718e12b elementor-widget elementor-widget-text-editor\" data-id=\"718e12b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.instagram.com\/antisaeroketa\/\" data-wplink-edit=\"true\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65018f6 elementor-widget elementor-widget-text-editor\" data-id=\"65018f6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Centro+Empresarial+Pereira+Barreto+-+CEPB\/@-23.6793126,-46.5406906,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce5cdb4b302603:0x2fd6b99920b581bf!8m2!3d-23.6793126!4d-46.5381157!16s%2Fg%2F11q463g815?entry=tts&amp;g_ep=EgoyMDI1MDUwMy4wIPu8ASoASAFQAw%3D%3D&amp;skid=5e6c9851-f843-4c45-a4ab-115e0ce321fa\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Av. Pereira Barreto, n\u00b0 1395 \u2013 Para\u00edso, Santo Andr\u00e9 \u2013 SP, 09190-610 \u2013 loja 03, T\u00e9rreo<em>\u00a0<\/em><\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-29f144e\" data-id=\"29f144e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-6a56e98\" data-id=\"6a56e98\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2268a71 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"2268a71\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/11\/61213e79-19cf-45b7-8102-e6e23617c097.jpg\" alt=\"61213e79-19cf-45b7-8102-e6e23617c097\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/11\/a4f5b133-cf66-4014-8677-0416e316aed6.jpg\" alt=\"a4f5b133-cf66-4014-8677-0416e316aed6\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/11\/dea58fa9-8921-41a5-87d9-c5328aac3632.jpg\" alt=\"dea58fa9-8921-41a5-87d9-c5328aac3632\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/11\/IMG_7573-768x432.jpg\" alt=\"IMG_7573\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/11\/IMG_7575-768x432.jpg\" alt=\"IMG_7575\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e43cdd5 elementor-widget elementor-widget-heading\" data-id=\"e43cdd5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Arccos Bar e Restaurante\n\n<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-733f176 elementor-widget elementor-widget-text-editor\" data-id=\"733f176\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.instagram.com\/arccosbar\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3900b15 elementor-widget elementor-widget-text-editor\" data-id=\"3900b15\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Arccos+Restaurante+Bar\/@-23.6609224,-46.5405853,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce43531194bfed:0x9b0574dbaaf145c7!8m2!3d-23.6609273!4d-46.5380104!16s%2Fg%2F11y7hhhw1s?entry=tts&amp;g_ep=EgoyMDI1MDUwMy4wIPu8ASoASAFQAw%3D%3D&amp;skid=53d30e6b-ea47-4e7d-b7d3-7cdeea158d1a\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong style=\"font-family: Roboto, sans-serif; font-size: 15px; font-style: normal; text-align: justify;\">Av. Lino Jardim, 558 \u2013 Vila Bastos, Santo Andr\u00e9 \u2013 SP, 09041-030<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-f0d763d\" data-id=\"f0d763d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-6ef5b2d\" data-id=\"6ef5b2d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-720abbb elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"720abbb\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/566f675b-11f3-4308-9221-ddfa2281e4e3-1.jpg\" alt=\"566f675b-11f3-4308-9221-ddfa2281e4e3\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/5735a5d5-373e-4b14-9f29-2b22a2f5c54d-1.jpg\" alt=\"5735a5d5-373e-4b14-9f29-2b22a2f5c54d\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/d5a56c4e-9fe9-475c-9969-22ba8b1c52a1-1.jpg\" alt=\"d5a56c4e-9fe9-475c-9969-22ba8b1c52a1\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51d8b89 elementor-widget elementor-widget-heading\" data-id=\"51d8b89\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Assule Comida \u00c1rabe<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5eed00f elementor-widget elementor-widget-text-editor\" data-id=\"5eed00f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.instagram.com\/assule_comida_arabe\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8029491 elementor-widget elementor-widget-text-editor\" data-id=\"8029491\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Assule+Comida+%C3%81rabe\/@-23.66609,-46.5259438,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce43b75052c19d:0x1615af3db1c2c8bd!8m2!3d-23.66609!4d-46.5259438!16s%2Fg%2F11vsrx42hn?entry=ttu&amp;g_ep=EgoyMDI1MDYwOS4xIKXMDSoASAFQAw%3D%3D\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Rua Cel. Ortiz, 459 \u2013 Vila Assun\u00e7\u00e3o, Santo Andr\u00e9 \u2013 SP, 09030-320<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-be5b145 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"be5b145\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3f97e73\" data-id=\"3f97e73\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b73d984 elementor-widget elementor-widget-spacer\" data-id=\"b73d984\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-34d20a1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"34d20a1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-8f6e15c\" data-id=\"8f6e15c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3096771 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"3096771\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-16-at-15.25.01-2.jpeg\" alt=\"WhatsApp Image 2024-05-16 at 15.25.01 (2)\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-16-at-15.25.02-768x432.jpeg\" alt=\"WhatsApp Image 2024-05-16 at 15.25.02\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-16-at-15.25.01-1.jpeg\" alt=\"WhatsApp Image 2024-05-16 at 15.25.01 (1)\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-16-at-15.25.01.jpeg\" alt=\"WhatsApp Image 2024-05-16 at 15.25.01\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-576e73d elementor-widget elementor-widget-heading\" data-id=\"576e73d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Baby Beef Jardim<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa9b493 elementor-widget elementor-widget-text-editor\" data-id=\"fa9b493\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/restaurantebbj\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/babybeefjardim\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a href=\"https:\/\/www.babybeefjardim.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a5a4be1 elementor-widget elementor-widget-text-editor\" data-id=\"a5a4be1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps?sca_esv=19fb95802b09d0d0&amp;rlz=1C1GCEU_pt-BRBR1098BR1098&amp;output=search&amp;q=Rua+das+Bandeiras,+166+B.+Jardim+-+Santo+Andr%C3%A9+\/+SP&amp;source=lnms&amp;entry=mc&amp;ved=1t:200715&amp;ictx=111\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Rua das Bandeiras, 166 &#8211; Jardim<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-79d1444\" data-id=\"79d1444\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-eb642c6\" data-id=\"eb642c6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e01fd0e elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"e01fd0e\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/balderi.png\" alt=\"balderi\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/balderi1.png\" alt=\"balderi1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/balderi2.png\" alt=\"balderi2\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/balderi3.png\" alt=\"balderi3\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b54890 elementor-widget elementor-widget-heading\" data-id=\"8b54890\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Balderi Pasta e Arte<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5360247 elementor-widget elementor-widget-text-editor\" data-id=\"5360247\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/balderi\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/balderi_pasta\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a href=\"https:\/\/balderi.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f807e24 elementor-widget elementor-widget-text-editor\" data-id=\"f807e24\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/R.+Tabaiares,+142+-+Vila+Assun%C3%A7%C3%A3o,+Santo+Andr%C3%A9+-+SP,+09030-360\/@-23.6665051,-46.5331111,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce4262290feb63:0x550d3002b3cefdf9!8m2!3d-23.6665051!4d-46.5305362!16s%2Fg%2F11vt9nb9sy?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Rua Tabaiares, 142 -Vila Assun\u00e7\u00e3o<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-78f7aba\" data-id=\"78f7aba\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-47d9078\" data-id=\"47d9078\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6160ceb elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"6160ceb\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/banka1.png\" alt=\"banka1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/banka2-768x432.png\" alt=\"banka2\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/banka4-768x432.png\" alt=\"banka4\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7062d2 elementor-widget elementor-widget-heading\" data-id=\"b7062d2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Banka Comida e Arte<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b1b673 elementor-widget elementor-widget-text-editor\" data-id=\"4b1b673\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/bankaoficial\/?locale=pt_BR\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/banka_oficial\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-410f017 elementor-widget elementor-widget-text-editor\" data-id=\"410f017\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps?sca_esv=97634d0872045a02&amp;rlz=1C1GCEU_pt-BRBR1098BR1098&amp;output=search&amp;q=R.+Santo+Andr%C3%A9,+182+-+Centro&amp;source=lnms&amp;entry=mc&amp;ved=1t:200715&amp;ictx=111\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Rua Santo Andr\u00e9, 182 &#8211; Centro<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4954723 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4954723\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3efed84\" data-id=\"3efed84\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a2f52a7 elementor-widget elementor-widget-spacer\" data-id=\"a2f52a7\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-62a1d56\" data-id=\"62a1d56\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20b6451 elementor-widget elementor-widget-spacer\" data-id=\"20b6451\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-553e641 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"553e641\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-d7106c7\" data-id=\"d7106c7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-97c4950 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"97c4950\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/bar-da-Dalva-768x432.jpg\" alt=\"bar da Dalva\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/bar-da-Dalva-1-768x432.jpg\" alt=\"bar da Dalva 1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/dalva1-768x432.jpg\" alt=\"dalva1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/dalva-1-768x432.jpg\" alt=\"dalva\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf7c69f elementor-widget elementor-widget-heading\" data-id=\"bf7c69f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Bar da Dalva<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e0b83d9 elementor-widget elementor-widget-text-editor\" data-id=\"e0b83d9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/bardadalvasantondre\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/bardadalva\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a href=\"https:\/\/www.canva.com\/design\/DAEH-Q-Z_uY\/SHZR2jS8m5R2IaCFoZADOA\/view?website#1\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19c6f48 elementor-widget elementor-widget-text-editor\" data-id=\"19c6f48\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Bar+da+Dalva\/@-23.6503343,-46.5441215,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce42e81efec7af:0x92c1580a5a639ae5!8m2!3d-23.6503343!4d-46.5441215!16s%2Fg%2F11b6hlhmfb?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Rua das Goiabeiras, 802 &#8211; Jardim<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-885bb8d\" data-id=\"885bb8d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-138c7e7\" data-id=\"138c7e7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-90d6dc9 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"90d6dc9\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/bar-figueiras-768x432.jpg\" alt=\"bar figueiras\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/bar-figueiras-5.jpg\" alt=\"bar figueiras 5\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/bar-figueiras-1.jpg\" alt=\"bar figueiras 1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/bar-figueiras-2.png\" alt=\"bar figueiras 2\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-887f561 elementor-widget elementor-widget-heading\" data-id=\"887f561\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Bar Figueiras<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f799c9d elementor-widget elementor-widget-text-editor\" data-id=\"f799c9d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/barfigueiras\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/barfigueiras\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a href=\"http:\/\/www.barfigueiras.com.br\/index.html\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1cb162c elementor-widget elementor-widget-text-editor\" data-id=\"1cb162c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/R.+das+Figueiras,+835+-+Jardim,+Santo+Andr%C3%A9+-+SP,+09080-370\/@-23.6500617,-46.5392144,15z\/data=!4m16!1m9!3m8!1s0x94ce42ea3921140d:0xb844379954331eb4!2sR.+das+Figueiras,+835+-+Jardim,+Santo+Andr%C3%A9+-+SP,+09080-370!3b1!8m2!3d-23.6500735!4d-46.5393!10e5!16s%2Fg%2F11cshpkpfy!3m5!1s0x94ce42ea3921140d:0xb844379954331eb4!8m2!3d-23.6500735!4d-46.5393!16s%2Fg%2F11cshpkpfy?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Rua das Figueiras, 835 &#8211; Jardim<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-687ff6e\" data-id=\"687ff6e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-7635da1\" data-id=\"7635da1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c7017e8 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"c7017e8\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/bardalino-2.jpg\" alt=\"bardalino 2\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/bardalino1.jpg\" alt=\"bardalino1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/bardalino3.jpg\" alt=\"bardalino3\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/bardalino.jpg\" alt=\"bardalino\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f42b108 elementor-widget elementor-widget-heading\" data-id=\"f42b108\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Bardalino<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a4dd83 elementor-widget elementor-widget-text-editor\" data-id=\"2a4dd83\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/bardalino\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/bardalinodelcarmem\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2dd77fe elementor-widget elementor-widget-text-editor\" data-id=\"2dd77fe\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Av.+Lino+Jardim,+713+-+Vila+Bastos,+Santo+Andr%C3%A9+-+SP,+09041-031\/@-23.6622384,-46.5383625,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce42f386058819:0x5bd10ff1716fa255!8m2!3d-23.6622384!4d-46.5383625!16s%2Fg%2F11cs76pqsm?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Av. Lino Jardim, 713 &#8211; Vila Bastos<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ee42069 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ee42069\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-201ed10\" data-id=\"201ed10\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0992849 elementor-widget elementor-widget-spacer\" data-id=\"0992849\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f30fcfc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f30fcfc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-0785979\" data-id=\"0785979\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52c6d95 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"52c6d95\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/095f80d1-0825-47e3-a9d9-13a8c29983fb-768x432.jpg\" alt=\"095f80d1-0825-47e3-a9d9-13a8c29983fb\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/31612291-f1a6-4ed6-a97e-7cb2383af7cc-768x432.jpg\" alt=\"31612291-f1a6-4ed6-a97e-7cb2383af7cc\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42c0be2 elementor-widget elementor-widget-heading\" data-id=\"42c0be2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Bassan Emp\u00f3rio<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-365c424 elementor-widget elementor-widget-text-editor\" data-id=\"365c424\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.facebook.com\/bassanemporio\/?locale=pt_BR\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.instagram.com\/bassanemporio\/?hl=pt\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/bassan-emporio.goomer.app\/?retry=true\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f047310 elementor-widget elementor-widget-text-editor\" data-id=\"f047310\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/maps.app.goo.gl\/yFHbz6UPh1aFxSGC8\"><img loading=\"lazy\" class=\"alignnone\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><br \/><b>Rua Su\u00ed\u00e7a, 879 &#8211;\u00a0<\/b><strong><span style=\"color: #1f1f1f; font-family: Arial, sans-serif; font-size: 14px; font-style: normal;\">Parque das Na\u00e7\u00f5es<\/span><\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-3d6da2e\" data-id=\"3d6da2e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-531be45\" data-id=\"531be45\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f26bc6 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"4f26bc6\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/bedito1-768x432.png\" alt=\"bedito1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/bendito-768x432.png\" alt=\"bendito\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/bendito2-768x432.png\" alt=\"bendito2\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cd9eac9 elementor-widget elementor-widget-heading\" data-id=\"cd9eac9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Bendito Ben\u00ea<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-114227c elementor-widget elementor-widget-text-editor\" data-id=\"114227c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.facebook.com\/benditobeneoficial\/?locale=pt_BR\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.instagram.com\/benditobeneoficial\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.ifood.com.br\/delivery\/santo-andre-sp\/bendito-bene--massas-e-pratos-artesanais-campestre\/bcc2aba0-7f87-4f16-b274-e30a4aa7d78e?utm_medium=share&amp;fbclid=IwZXh0bgNhZW0CMTAAAR0JVSH-rUzjJdKIP0tpHJoaWy3Jon5ArKJdvHX7bkbB-AZUh3CJ7dkhZ_g_aem_AYaaNM3Zz705Wq13f0mSjrlqmSXkkLMOmz7YDTHABfhz7z6SmCAgneNBrv_ofOv1Ion7J3R-mcI2asGR03tgQiTd\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09d7555 elementor-widget elementor-widget-text-editor\" data-id=\"09d7555\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Av.+Dom+Pedro+II,+1679+-+Campestre,+Santo+Andr%C3%A9+-+SP,+09080-111\/@-23.641821,-46.5429737,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce42c42abecd8f:0xdd074c692d8e0c43!8m2!3d-23.641821!4d-46.5403988!16s%2Fg%2F11c22ydbb9?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Av. Dom Pedro II,1679- Campestre<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-d4687ed\" data-id=\"d4687ed\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-88d7275\" data-id=\"88d7275\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f1090a elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"2f1090a\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/berlim-768x432.jpg\" alt=\"berlim\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/berlim1-768x432.jpg\" alt=\"berlim1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/berlim-1-768x432.jpg\" alt=\"berlim\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1223c99 elementor-widget elementor-widget-heading\" data-id=\"1223c99\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Berlin Costelaria<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-201818c elementor-widget elementor-widget-text-editor\" data-id=\"201818c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.facebook.com\/berlin.santoandre\/?locale=pt_BR\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.instagram.com\/berlin.costelaria\/?hl=pt\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.berlin.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f8d5e5 elementor-widget elementor-widget-text-editor\" data-id=\"9f8d5e5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Berlin+Costelaria\/@-23.6478348,-46.5473113,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce42c32db44947:0x52f074ce1ce3ef41!8m2!3d-23.6478397!4d-46.5447364!16s%2Fg%2F1tglp026?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Alameda S\u00e3o Caetano, 719 &#8211; Jardim<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-533717b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"533717b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-31e25d6\" data-id=\"31e25d6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c01ada elementor-widget elementor-widget-spacer\" data-id=\"6c01ada\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-22f6899 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"22f6899\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-60a5d3e\" data-id=\"60a5d3e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7539b9f elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"7539b9f\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/cimer1.png\" alt=\"cimer1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/cimer3.png\" alt=\"cimer3\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/bistro-cimer-768x432.png\" alt=\"bistro cimer\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/cimer-1.png\" alt=\"cimer\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-550d14a elementor-widget elementor-widget-heading\" data-id=\"550d14a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Bistr\u00f4 Cimer<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e652d5 elementor-widget elementor-widget-text-editor\" data-id=\"7e652d5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.instagram.com\/cimerbistrot\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.cimerbistrot.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56548c1 elementor-widget elementor-widget-text-editor\" data-id=\"56548c1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps?sca_esv=f4dacfe81c780abe&amp;sca_upv=1&amp;rlz=1C1GCEU_pt-BRBR1098BR1098&amp;output=search&amp;q=shopping+abc&amp;source=lnms&amp;entry=mc&amp;utm_campaign=srp-cst&amp;ved=1t:200715&amp;ictx=111\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Av. Pereira Barreto, 42 &#8211; Vl. Gilda\u00a0 &#8211; Shopping ABC<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-b2fc9f2\" data-id=\"b2fc9f2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-0c70f1e\" data-id=\"0c70f1e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eaa7d88 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"eaa7d88\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/8f611e85-c4ce-4ee6-8afa-a7c46caff77f-1-768x432.jpg\" alt=\"8f611e85-c4ce-4ee6-8afa-a7c46caff77f\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/YAKISOBA_BOLASUSHI-1-2-768x432.png\" alt=\"YAKISOBA_BOLASUSHI (1)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb83c26 elementor-widget elementor-widget-heading\" data-id=\"eb83c26\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">BolaSushi<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-635aa7c elementor-widget elementor-widget-text-editor\" data-id=\"635aa7c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.instagram.com\/bolasushi\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"www.bolasushi.com.br\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c672e6 elementor-widget elementor-widget-text-editor\" data-id=\"8c672e6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/maps.app.goo.gl\/hTkyEYK8EAxeZBX47\"><img loading=\"lazy\" class=\"alignnone\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><br \/><b>Av. dos Estados, 4430 &#8211; Vila Metal\u00fargica\u00a0<\/b><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-1d04e0d\" data-id=\"1d04e0d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-76cf1c6\" data-id=\"76cf1c6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8e7013c elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"8e7013c\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/5a286048-edfe-411a-bc73-9a91ddc534a5-1-768x432.jpg\" alt=\"5a286048-edfe-411a-bc73-9a91ddc534a5\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/779f07d1-bee1-48c4-931c-eade943fec70-1-768x432.jpg\" alt=\"779f07d1-bee1-48c4-931c-eade943fec70\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/d78fed86-4a39-4274-a73b-544b6f7374fa-1-768x432.jpg\" alt=\"d78fed86-4a39-4274-a73b-544b6f7374fa\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc7c6e6 elementor-widget elementor-widget-heading\" data-id=\"cc7c6e6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Bom Bowls<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-521f4ef elementor-widget elementor-widget-text-editor\" data-id=\"521f4ef\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.facebook.com\/bombowlsfood\/?locale=pt_BR\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.instagram.com\/bombowls_\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.bombowls.com.br\/site\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e727b94 elementor-widget elementor-widget-text-editor\" data-id=\"e727b94\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/maps.app.goo.gl\/TMWUKtd9uppbXK2f9\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><b>Rua Haddock Lobo, 341 &#8211; Vila Bastos\u00a0<\/b><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1e95c88 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1e95c88\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2a709f1\" data-id=\"2a709f1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3088bc0 elementor-widget elementor-widget-spacer\" data-id=\"3088bc0\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bc9cd78 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bc9cd78\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-f575bc9\" data-id=\"f575bc9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-91316b3 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"91316b3\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/5-768x432.png\" alt=\"5\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/cinco-768x432.png\" alt=\"cinco\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/cinco2.png\" alt=\"cinco2\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/cinco3-768x432.png\" alt=\"cinco3\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-80eba1c elementor-widget elementor-widget-heading\" data-id=\"80eba1c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Boteco 5 Esquinas<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e67467e elementor-widget elementor-widget-text-editor\" data-id=\"e67467e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/boteco5esquinas\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/boteco5esquinas\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a href=\"https:\/\/www.boteco5esquinas.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65698c0 elementor-widget elementor-widget-text-editor\" data-id=\"65698c0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/R.+Cel.+Francisco+Amaro,+1+-+Centro,+Santo+Andr%C3%A9+-+SP,+09020-250\/@-23.6595503,-46.5253696,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce42871d16654b:0xdd28ef210f8d4c48!8m2!3d-23.6595503!4d-46.5227947!16s%2Fg%2F11c5mdjf8b?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Rua Cel. Francisco Amaro, 1 &#8211; Centro<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-c4d6f5e\" data-id=\"c4d6f5e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-2d3c397\" data-id=\"2d3c397\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-391808a elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"391808a\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/Donna-Vitoria-fachada-1.jpg\" alt=\"Donna-Vitoria-fachada-1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/Donna2.jpg\" alt=\"Donna2\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/Donna3.jpg\" alt=\"Donna3\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/Donna5.jpg\" alt=\"Donna5\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cbad41b elementor-widget elementor-widget-heading\" data-id=\"cbad41b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Boteco Donna Vit\u00f3ria<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f8c445 elementor-widget elementor-widget-text-editor\" data-id=\"2f8c445\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/botecodonnaviitoria\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/botecodonnavitoria\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a href=\"https:\/\/pdf.qrcoo.de\/392-62df06029aff9-d188e6b1f969fac24e68.pdf\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3593f08 elementor-widget elementor-widget-text-editor\" data-id=\"3593f08\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Boteco+Donna+Vit%C3%B3ria\/@-23.6615165,-46.540965,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce43f98301e0ad:0x64fa26a1c9f88820!8m2!3d-23.6615214!4d-46.5383901!16s%2Fg%2F11qpmzplkh?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Av. Lino Jardim, 646 &#8211; Vila Bastos<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-2909fd8\" data-id=\"2909fd8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-ded62df\" data-id=\"ded62df\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d15758 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"3d15758\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/boteco-1-maria-1024x682-1-768x432.jpg\" alt=\"boteco 1-maria-1024x682\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/Boteco2-Maria-Ambiente-4-h-460x460-1.jpg\" alt=\"Boteco2-Maria-Ambiente-4-h-460x460\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/maria1.png\" alt=\"maria1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/maria.png\" alt=\"maria\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c67411 elementor-widget elementor-widget-heading\" data-id=\"6c67411\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Boteco Maria<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83c4f5a elementor-widget elementor-widget-text-editor\" data-id=\"83c4f5a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/BotecoMaria\/?locale=pt_BR\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/botecomaria\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a href=\"http:\/\/botecomaria.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fea20e2 elementor-widget elementor-widget-text-editor\" data-id=\"fea20e2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Boteco+Maria\/@-23.653568,-46.534271,15z\/data=!4m2!3m1!1s0x0:0xeb55e05fd23f8010?sa=X&amp;ved=2ahUKEwjMpanIo7qEAxUWSLgEHcOgCw8Q_BJ6BAgSEAA\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Av. Padre Manuel da N\u00f3brega, 216 &#8211; Jardim<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3f42aaf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f42aaf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4a10279\" data-id=\"4a10279\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9353364 elementor-widget elementor-widget-spacer\" data-id=\"9353364\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-239f9ee elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"239f9ee\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-b91880d\" data-id=\"b91880d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4aaaeb7 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"4aaaeb7\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/scarpelli-768x432.jpg\" alt=\"scarpelli\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/scarpelli1-768x432.jpg\" alt=\"scarpelli1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/scarpelli2-768x432.jpg\" alt=\"scarpelli2\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/scarpelli3-768x432.jpg\" alt=\"scarpelli3\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e372f3 elementor-widget elementor-widget-heading\" data-id=\"6e372f3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Botequim Scarpelli<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8f405f elementor-widget elementor-widget-text-editor\" data-id=\"d8f405f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/pages\/Botequim%20Scarpelli\/100729184730251\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/botequimscarpelli\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f46dba8 elementor-widget elementor-widget-text-editor\" data-id=\"f46dba8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps?sca_esv=73a5863c59a470b2&amp;sca_upv=1&amp;rlz=1C1GCEU_pt-BRBR1098BR1098&amp;output=search&amp;q=Rua+Senador+Queiroz,+780&amp;source=lnms&amp;entry=mc&amp;ved=1t:200715&amp;ictx=111\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Rua Sen. Queir\u00f3s, 780 &#8211; Vila Scarpelli<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-fe2e219\" data-id=\"fe2e219\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-49e87f1\" data-id=\"49e87f1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-90b2fdb elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"90b2fdb\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/brutta-768x432.png\" alt=\"brutta\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/brutta1-768x432.png\" alt=\"brutta1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/brutta3-768x432.png\" alt=\"brutta3\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/brutta4-768x432.png\" alt=\"brutta4\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a72b72 elementor-widget elementor-widget-heading\" data-id=\"4a72b72\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Brutta Mama<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f153605 elementor-widget elementor-widget-text-editor\" data-id=\"f153605\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.instagram.com\/bruttamamma\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a href=\"https:\/\/www.canva.com\/design\/DAFnogH3B5k\/_WrX7WODv32IrW1Wr4AuoA\/view#4\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34c44f1 elementor-widget elementor-widget-text-editor\" data-id=\"34c44f1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/R.+%C3%81lvares+de+Azevedo,+148+-+Centro,+Santo+Andr%C3%A9+-+SP,+09020-140\/@-23.6583629,-46.5315037,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce428ecf742a1b:0x123ddc18415cb568!8m2!3d-23.6583629!4d-46.5289288!16s%2Fg%2F11csm13k_b?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Rua \u00c1lvares de Azevedo, 148 &#8211; Centro\u00a0<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-4f22d45\" data-id=\"4f22d45\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-b72f00f\" data-id=\"b72f00f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56adc07 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"56adc07\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/06\/caboclo.png\" alt=\"caboclo\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/06\/caboclo1.png\" alt=\"caboclo1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/06\/caboclo3.png\" alt=\"caboclo3\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cd73105 elementor-widget elementor-widget-heading\" data-id=\"cd73105\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Cabloco B\u00e3o<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-61cbdbf elementor-widget elementor-widget-text-editor\" data-id=\"61cbdbf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/profile.php?id=100086219303265\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/caboclo_bao\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ddda7ae elementor-widget elementor-widget-text-editor\" data-id=\"ddda7ae\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/R.+Gertr%C3%BAdes+de+Lima,+356+-+Centro,+Santo+Andr%C3%A9+-+SP,+09020-000\/@-23.6623424,-46.5279056,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce4287fa2fb4bb:0x6cbebddc1d09fb2e!8m2!3d-23.6623424!4d-46.5253307!16s%2Fg%2F11c4ybq_1f?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>R. Gertr\u00fades de Lima, 356 &#8211; Centro<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dd3d404 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dd3d404\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2966d1b\" data-id=\"2966d1b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f7dd17 elementor-widget elementor-widget-spacer\" data-id=\"6f7dd17\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9132461 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9132461\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-b71dbde\" data-id=\"b71dbde\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4057bcf elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"4057bcf\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/caiana1.png\" alt=\"caiana1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/caiana3.png\" alt=\"caiana3\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/caiana.png\" alt=\"caiana\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3f5e22 elementor-widget elementor-widget-heading\" data-id=\"e3f5e22\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Caiana Bar &amp; Gastronomia<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e142848 elementor-widget elementor-widget-text-editor\" data-id=\"e142848\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/p\/Caiana-Bar-e-Gastronomia-100076130243647\/?locale=ms_MY\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/caianabuffet\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a href=\"https:\/\/caianagastronomia.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-debf17b elementor-widget elementor-widget-text-editor\" data-id=\"debf17b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Grand+Plaza+Shopping\/@-23.6487368,-46.5346137,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce4294ff676307:0xd9bb1a8238ff865a!8m2!3d-23.6487368!4d-46.5320388!16s%2Fg%2F120l7rzg?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Av. Industrial, 600 &#8211; Centro &#8211; Grand Plaza Shopping<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-3f01a19\" data-id=\"3f01a19\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-720c6be\" data-id=\"720c6be\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a20187 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"3a20187\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/calle1.png\" alt=\"calle1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/calle2.png\" alt=\"calle2\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/calle3.png\" alt=\"calle3\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf98e30 elementor-widget elementor-widget-heading\" data-id=\"cf98e30\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Calle 54<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b13f9a8 elementor-widget elementor-widget-text-editor\" data-id=\"b13f9a8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/calle54abc?locale=ms_MY\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/caianabuffet\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a href=\"https:\/\/www.calle54.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5020245 elementor-widget elementor-widget-text-editor\" data-id=\"5020245\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps?sca_esv=f4dacfe81c780abe&amp;sca_upv=1&amp;rlz=1C1GCEU_pt-BRBR1098BR1098&amp;output=search&amp;q=shopping+abc&amp;source=lnms&amp;entry=mc&amp;utm_campaign=srp-cst&amp;ved=1t:200715&amp;ictx=111\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Av. Pereira Barreto, 42 &#8211; Vl. Gilda\u00a0 &#8211; Shopping ABC<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-f365cdc\" data-id=\"f365cdc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-36dbe24\" data-id=\"36dbe24\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0c23a7f elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"0c23a7f\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/camarada-1.png\" alt=\"camarada\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/camarada1.png\" alt=\"camarada1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/camarada2.png\" alt=\"camarada2\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/camarada3.png\" alt=\"camarada3\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c14bb4 elementor-widget elementor-widget-heading\" data-id=\"0c14bb4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Camarada Camar\u00e3o<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13b2932 elementor-widget elementor-widget-text-editor\" data-id=\"13b2932\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.facebook.com\/profile.php?id=100084728035679&amp;locale=pt_BR\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.instagram.com\/camaradacamarao\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.ocamarada.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22fa5c7 elementor-widget elementor-widget-text-editor\" data-id=\"22fa5c7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Grand+Plaza+Shopping\/@-23.6487368,-46.5346137,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce4294ff676307:0xd9bb1a8238ff865a!8m2!3d-23.6487368!4d-46.5320388!16s%2Fg%2F120l7rzg?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Av. Industrial, 600 &#8211; Centro &#8211; Grand Plaza Shopping<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9661828 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9661828\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a883491\" data-id=\"a883491\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c7e13a6 elementor-widget elementor-widget-spacer\" data-id=\"c7e13a6\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-02c29e7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"02c29e7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-7c5dbb9\" data-id=\"7c5dbb9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-408117f elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"408117f\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/camargos.png\" alt=\"camargos\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/camargos1.png\" alt=\"camargos1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/camargos2.png\" alt=\"camargos2\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/camargos3.png\" alt=\"camargos3\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c2ff02 elementor-widget elementor-widget-heading\" data-id=\"2c2ff02\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Camargo`s Bar<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df58d56 elementor-widget elementor-widget-text-editor\" data-id=\"df58d56\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/profile.php?id=61555151285422\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/camargos.bar\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e490f22 elementor-widget elementor-widget-text-editor\" data-id=\"e490f22\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Av.+Padre+Manuel+da+N%C3%B3brega,+340+-+Jardim,+Santo+Andr%C3%A9+-+SP,+09080-140\/@-23.6526342,-46.537435,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce42934662556d:0xe2dcd62da3ffef00!8m2!3d-23.6526342!4d-46.5348601!16s%2Fg%2F11cpkqffxl?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Av. Padre Manuel da N\u00f3brega, 340 &#8211; Jardim<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-4c9a861\" data-id=\"4c9a861\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-a629ad2\" data-id=\"a629ad2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ff35ce elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"6ff35ce\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/casa-1.png\" alt=\"casa\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/casa1-1.png\" alt=\"casa1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/casa-2.png\" alt=\"casa\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/casa2-1.png\" alt=\"casa2\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-449b971 elementor-widget elementor-widget-heading\" data-id=\"449b971\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Casa Dom Bernardo<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c909e8 elementor-widget elementor-widget-text-editor\" data-id=\"6c909e8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/casadombernardo\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/casadombernardo\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a href=\"https:\/\/casadombernardo.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0006ae5 elementor-widget elementor-widget-text-editor\" data-id=\"0006ae5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Grand+Plaza+Shopping\/@-23.6487368,-46.5346137,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce4294ff676307:0xd9bb1a8238ff865a!8m2!3d-23.6487368!4d-46.5320388!16s%2Fg%2F120l7rzg?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Rua das Aroeiras, 510 &#8211;\u00a0 Jardim<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-8cbc2c1\" data-id=\"8cbc2c1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-c66dd03\" data-id=\"c66dd03\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-57c8ec9 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"57c8ec9\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/casantiga-1.jpg\" alt=\"casantiga\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/casantiga1-1-768x432.jpg\" alt=\"casantiga1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/casantiga2-1.png\" alt=\"casantiga2\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8eb5523 elementor-widget elementor-widget-heading\" data-id=\"8eb5523\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Casantiga Pizzaria e Restaurante<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-acdc64e elementor-widget elementor-widget-text-editor\" data-id=\"acdc64e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/casantigapizzariaerestaurante\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/casantigapizzaria\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a href=\"https:\/\/www.pizzariacasantiga.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97ec896 elementor-widget elementor-widget-text-editor\" data-id=\"97ec896\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Casantiga+Pizzaria+%26+Restaurante\/@-23.6663447,-46.527195,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce427c9438b23f:0x33ba4fbdb7563a9c!8m2!3d-23.6663447!4d-46.5246201!16s%2Fg%2F1tfk0zjs?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Pra\u00e7a Pres. Vargas, 67 &#8211; Vila Assun\u00e7\u00e3o<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5971ffd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5971ffd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d2fe10c\" data-id=\"d2fe10c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-efac714 elementor-widget elementor-widget-spacer\" data-id=\"efac714\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dee9c69 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dee9c69\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-877dec7\" data-id=\"877dec7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-00fa241 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"00fa241\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/coco.jpg\" alt=\"coco\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/cocob.jpg\" alt=\"cocob\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/cocob1-768x432.jpg\" alt=\"cocob1\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5de72db elementor-widget elementor-widget-heading\" data-id=\"5de72db\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Coco Bambu<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-847657b elementor-widget elementor-widget-text-editor\" data-id=\"847657b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.facebook.com\/profile.php?id=100087206172358&amp;ref=page_internal\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.instagram.com\/cocobambuabc\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/qr.cocobambu.com\/santoandre?fbclid=IwAR16xTP8SdbCEpT2eha6nSWVAzypznhZvfpizbsYRycszZg7Gzkkz26ZWdg\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6938b16 elementor-widget elementor-widget-text-editor\" data-id=\"6938b16\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Coco+Bambu+Santo+Andr%C3%A9:+Restaurante,+Peixe,+Camar%C3%A3o,+Carnes,+Lagosta,+Salada,+SP\/@-23.6668692,-46.5406561,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce437eceeb6899:0xbff514a195369935!8m2!3d-23.6668742!4d-46.5357852!16s%2Fg%2F11g_pjswv1?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Av. Portugal, 1362 &#8211; Centro<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-2097053\" data-id=\"2097053\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-5f48d35\" data-id=\"5f48d35\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0bedb56 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"0bedb56\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/coop1-768x432.png\" alt=\"coop1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/coop3.png\" alt=\"coop3\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/coop2-1-768x432.png\" alt=\"coop2\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-addd57f elementor-widget elementor-widget-heading\" data-id=\"addd57f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Coop Emp\u00f3rio <\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5101afe elementor-widget elementor-widget-text-editor\" data-id=\"5101afe\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/portalcoop\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/portalcoop\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a href=\"https:\/\/www.portalcoop.com.br\/coop-emporio\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09876fe elementor-widget elementor-widget-text-editor\" data-id=\"09876fe\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com.br\/maps\/place\/Av.+Portugal,+777+-+Centro,+Santo+Andr%C3%A9+-+SP,+09040-011\/@-23.662677,-46.5329053,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce428babdfbe5d:0xfc55c98af895fa51!8m2!3d-23.662677!4d-46.5329053!16s%2Fg%2F11bw3x88l8?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Av. Portugal, 777 &#8211; Centro\u00a0<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-b8fef74\" data-id=\"b8fef74\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-d3edf00\" data-id=\"d3edf00\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a880b9 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"3a880b9\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/caracao1.png\" alt=\"cara\u00e7\u00e3o1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/coracao2.png\" alt=\"cora\u00e7\u00e3o2\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/coracao3.png\" alt=\"cora\u00e7\u00e3o3\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ecffe1f elementor-widget elementor-widget-heading\" data-id=\"ecffe1f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Cora\u00e7\u00e3o Mineiro<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-052f57f elementor-widget elementor-widget-text-editor\" data-id=\"052f57f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/coracaomineirorestauranteoficial?locale=ms_MY\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/coracaomineirooficial\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" data-wp-editing=\"1\" \/><\/a><a href=\"https:\/\/coracaomineiro.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69c2121 elementor-widget elementor-widget-text-editor\" data-id=\"69c2121\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Grand+Plaza+Shopping\/@-23.6487368,-46.5346137,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce4294ff676307:0xd9bb1a8238ff865a!8m2!3d-23.6487368!4d-46.5320388!16s%2Fg%2F120l7rzg?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Av. Industrial, 600 &#8211; Centro &#8211; Grand Plaza Shopping<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e3eb07 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2e3eb07\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-36b01d4\" data-id=\"36b01d4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e523ad0 elementor-widget elementor-widget-spacer\" data-id=\"e523ad0\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-01608fd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"01608fd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-b0d6841\" data-id=\"b0d6841\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c638479 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"c638479\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/coz.png\" alt=\"coz\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/coz1-768x432.png\" alt=\"coz1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/coz2-768x432.png\" alt=\"coz2\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/coz4-768x432.png\" alt=\"coz4\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52ddefe elementor-widget elementor-widget-heading\" data-id=\"52ddefe\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><h5 data-elementor-setting-key=\"title\" data-pen-placeholder=\"Digite aqui...\" style=\"font-style: normal;\">Cozinha Campestre Restaurante e Pizzaria<span style=\"color: rgb(51, 51, 51); font-family: Roboto, sans-serif; font-size: 18px; font-style: inherit; font-weight: 700; white-space: pre-wrap; text-align: center; background-color: rgb(255, 255, 255); display: inline !important; float: none;\"><\/span><\/h5><\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a590ad8 elementor-widget elementor-widget-text-editor\" data-id=\"a590ad8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/restaurantecozinhacampestre\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/restaurantecozinhacampestre\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a href=\"https:\/\/linktr.ee\/cozinhacampestre\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-80a7393 elementor-widget elementor-widget-text-editor\" data-id=\"80a7393\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/maps.app.goo.gl\/ET3rDT9Hf5A4sS7w8\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong><span class=\"w8qArf FoJoyf\" style=\"color: #1f1f1f; font-family: Arial, sans-serif; font-size: 14px; font-style: normal; text-align: start;\">\u00a0<\/span><span class=\"LrzXr\" style=\"color: #1f1f1f; font-family: Arial, sans-serif; font-size: 14px; font-style: normal; text-align: start;\">R. Porto Carrero, 285 &#8211; Campestre<\/span><\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-ce0089e\" data-id=\"ce0089e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-fbe5652\" data-id=\"fbe5652\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-116a5a9 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"116a5a9\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/costela-barbecue_08-1-768x432.jpg\" alt=\"costela barbecue_08 (1)\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/Croco_21-768x432.jpg\" alt=\"Croco_21\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/parmegiana_19-768x432.jpg\" alt=\"parmegiana_19\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5206777 elementor-widget elementor-widget-heading\" data-id=\"5206777\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Croco Gastrobar<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52647a2 elementor-widget elementor-widget-text-editor\" data-id=\"52647a2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/Croco.gastrobar\/?locale=pt_BR\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/croco.gastrobar\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a href=\"https:\/\/crocogastrobar.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f10947 elementor-widget elementor-widget-text-editor\" data-id=\"3f10947\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/maps.app.goo.gl\/98Kx6AgVekqVJqs87\"><img loading=\"lazy\" class=\"alignnone\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><br \/><b>Alameda S\u00e3o Caetano, 621 &#8211; Bairro Jardim<\/b><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-6945952\" data-id=\"6945952\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-2fb02bd\" data-id=\"2fb02bd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-314b0a4 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"314b0a4\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/cruz3-768x432.jpg\" alt=\"cruz3\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/cruz4-768x432.jpg\" alt=\"cruz4\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/cruz5-768x432.jpg\" alt=\"cruz5\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/cruz6-768x432.jpg\" alt=\"cruz6\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53d5b9a elementor-widget elementor-widget-heading\" data-id=\"53d5b9a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Cruzeiro's Bar<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9128625 elementor-widget elementor-widget-text-editor\" data-id=\"9128625\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/cruzeirosbarshopping\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/cruzeirosbar\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a href=\"https:\/\/cruzeirosbar.com.br\/santoandre\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1630494 elementor-widget elementor-widget-text-editor\" data-id=\"1630494\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Grand+Plaza+Shopping\/@-23.6487368,-46.5320388,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce4294ff676307:0xd9bb1a8238ff865a!8m2!3d-23.6487368!4d-46.5320388!16s%2Fg%2F120l7rzg?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Av. Industrial, 600 &#8211; Centro &#8211; Boulevard Gastron\u00f4mico &#8211; Grand Plaza Shopping\u00a0<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-53c8a83 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"53c8a83\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-affac31\" data-id=\"affac31\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0e81c30 elementor-widget elementor-widget-spacer\" data-id=\"0e81c30\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-30c7c47 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"30c7c47\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-f5e34d9\" data-id=\"f5e34d9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a4c8b0 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"7a4c8b0\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/brescia-768x432.jpg\" alt=\"brescia\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/brescia1-768x432.jpg\" alt=\"brescia1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/brescia4-768x432.jpg\" alt=\"brescia4\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/brescia3-1-768x432.jpg\" alt=\"brescia3\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-672ed19 elementor-widget elementor-widget-heading\" data-id=\"672ed19\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">D'Brescia Churrascaria<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-918c261 elementor-widget elementor-widget-text-editor\" data-id=\"918c261\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.facebook.com\/dbresciachurrascaria\/?locale=pt_BR\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.instagram.com\/dbresciachurrascaria\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"http:\/\/www.dbresciachurrascaria.com.br\/unidades\/santo-andre\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a5bbf2 elementor-widget elementor-widget-text-editor\" data-id=\"3a5bbf2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/D'Brescia+Churrascaria+%7C+Santo+Andr%C3%A9\/@-23.6515366,-46.5390258,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce429361d49b23:0x983cced20115e217!8m2!3d-23.6515416!4d-46.5341549!16s%2Fg%2F1tfp3k_q?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Av. Dom Pedro II, 444 &#8211; Jardim<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-1c9c755\" data-id=\"1c9c755\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-b5ccdaa\" data-id=\"b5ccdaa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e1e7990 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"e1e7990\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/divino.png\" alt=\"divino\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/divino1.png\" alt=\"divino1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/divino2.png\" alt=\"divino2\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ca081e elementor-widget elementor-widget-heading\" data-id=\"2ca081e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Divino Fog\u00e3o<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b597fc elementor-widget elementor-widget-text-editor\" data-id=\"3b597fc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/divinofogao\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/divino_fogao\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a href=\"https:\/\/www.divinofogao.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b792e2 elementor-widget elementor-widget-text-editor\" data-id=\"2b792e2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Grand+Plaza+Shopping\/@-23.6487368,-46.5346137,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce4294ff676307:0xd9bb1a8238ff865a!8m2!3d-23.6487368!4d-46.5320388!16s%2Fg%2F120l7rzg?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Av. Industrial, 600 &#8211; Centro &#8211; Grand Plaza Shopping<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-b349076\" data-id=\"b349076\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-de3da38\" data-id=\"de3da38\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8856a3f elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"8856a3f\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/hello4.png\" alt=\"hello4\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/hello1.png\" alt=\"hello1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/hello3.png\" alt=\"hello3\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15c1ffd elementor-widget elementor-widget-heading\" data-id=\"15c1ffd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Eat Asia + Hello Kit<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-026eab2 elementor-widget elementor-widget-text-editor\" data-id=\"026eab2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/eatasiabr\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/eatasiabr\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a href=\"https:\/\/eatasia.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4e4fe4 elementor-widget elementor-widget-text-editor\" data-id=\"c4e4fe4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Grand+Plaza+Shopping\/@-23.6487368,-46.5320388,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce4294ff676307:0xd9bb1a8238ff865a!8m2!3d-23.6487368!4d-46.5320388!16s%2Fg%2F120l7rzg?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Av. Industrial, 600 &#8211; Centro &#8211; Grand Plaza Shopping<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-07f1502 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"07f1502\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0f2b3cc\" data-id=\"0f2b3cc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9d3531b elementor-widget elementor-widget-spacer\" data-id=\"9d3531b\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-09928e0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"09928e0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-6d1a10d\" data-id=\"6d1a10d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fdf123d elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"fdf123d\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/11\/15af0afb-3850-4a67-81eb-d87fd4638396-768x432.jpg\" alt=\"15af0afb-3850-4a67-81eb-d87fd4638396\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/11\/150b89c9-16d0-47db-91c5-845fc285b2a2-768x432.jpg\" alt=\"150b89c9-16d0-47db-91c5-845fc285b2a2\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/11\/864ccbe2-e545-44da-8a6a-0f124e2ed4ff-768x432.jpg\" alt=\"864ccbe2-e545-44da-8a6a-0f124e2ed4ff\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/11\/83824a02-123c-425c-b395-9d1dad479850-768x432.jpg\" alt=\"83824a02-123c-425c-b395-9d1dad479850\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/11\/abb59a19-9acb-4cc0-a996-f261981a8832-768x432.jpg\" alt=\"abb59a19-9acb-4cc0-a996-f261981a8832\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/11\/c7153e36-5cf8-4217-8430-1b9e9c764929-768x432.jpg\" alt=\"c7153e36-5cf8-4217-8430-1b9e9c764929\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/11\/dbd5fe32-04c7-430a-a695-67dcb32b5de0-768x432.jpg\" alt=\"dbd5fe32-04c7-430a-a695-67dcb32b5de0\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77dff3c elementor-widget elementor-widget-heading\" data-id=\"77dff3c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Emp\u00f3rio Boulevard Jardim<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85469c1 elementor-widget elementor-widget-text-editor\" data-id=\"85469c1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/people\/Emp%C3%B3rio-Boulevard-Unidade-Jardim\/61551739637236\/?_rdr\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/emporioboulevardjardim\/?hl=pt\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04482be elementor-widget elementor-widget-text-editor\" data-id=\"04482be\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/maps.app.goo.gl\/oPwvZsKdznn9MfhP6\" data-wplink-edit=\"true\"><img loading=\"lazy\" class=\"alignnone\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><br \/><b>Av. Padre Manuel da N\u00f3brega, 382 &#8211; Bairro Jardim<\/b><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-ef955b0\" data-id=\"ef955b0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-b6ca131\" data-id=\"b6ca131\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e1bc85 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"4e1bc85\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/MG_6301-1-768x432.jpg\" alt=\"Deck Assun\u00e7\u00e3o\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/FACHADA-ASSUNCAO-768x432.jpeg\" alt=\"FACHADA ASSUN\u00c7\u00c3O\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b2defc elementor-widget elementor-widget-heading\" data-id=\"1b2defc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Emp\u00f3rio Sterci - Assun\u00e7\u00e3o<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-042e2aa elementor-widget elementor-widget-text-editor\" data-id=\"042e2aa\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/emporioassuncao\/?locale=pt_BR\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/emporiosterci_assuncao\/?hl=pt\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb7319a elementor-widget elementor-widget-text-editor\" data-id=\"cb7319a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/maps.app.goo.gl\/7H7riJR4gD8iJkwC7\"><img loading=\"lazy\" class=\"alignnone\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><br \/><b>Rua Dr. C\u00e9lso Gama, 118 &#8211; Vila Assun\u00e7\u00e3o<\/b><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-9683ea7\" data-id=\"9683ea7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-d9aa3c9\" data-id=\"d9aa3c9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1097a99 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"1097a99\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/farofa-768x432.jpg\" alt=\"farofa\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/farofa1.jpg\" alt=\"farofa1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/farofa3.jpg\" alt=\"farofa3\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/farofa4-768x432.jpg\" alt=\"farofa4\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6797855 elementor-widget elementor-widget-heading\" data-id=\"6797855\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Farofa Paulista<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e880493 elementor-widget elementor-widget-text-editor\" data-id=\"e880493\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.facebook.com\/restaurantefarofapaulista\/photos_by?locale=pt_BR\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.instagram.com\/farofapaulistasp\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d0879cb elementor-widget elementor-widget-text-editor\" data-id=\"d0879cb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Restaurante+Farofa+Paulista+em+Santo+Andr%C3%A9\/@-23.6675934,-46.4915947,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce69bd13d9c02b:0x93219c981c93f828!8m2!3d-23.6675934!4d-46.4890198!16s%2Fg%2F11gfj4tg9_?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Av. S\u00e3o Paulo, 355 &#8211; Cidade S\u00e3o Jorge<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7f6041c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7f6041c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2c03610\" data-id=\"2c03610\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a939c1f elementor-widget elementor-widget-spacer\" data-id=\"a939c1f\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ba14b63 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ba14b63\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-fca0737\" data-id=\"fca0737\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e04b957 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"e04b957\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/farra.png\" alt=\"farra\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/farra1.png\" alt=\"farra1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/farra4.png\" alt=\"farra4\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/farra5.png\" alt=\"farra5\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a23984 elementor-widget elementor-widget-heading\" data-id=\"3a23984\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Farra na Villa<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e80a946 elementor-widget elementor-widget-text-editor\" data-id=\"e80a946\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.facebook.com\/farranavilla?locale=pt_BR\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.instagram.com\/farranavilla\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.farranavilla.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db89b21 elementor-widget elementor-widget-text-editor\" data-id=\"db89b21\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Alameda+S%C3%A3o+Caetano,+395+-+Jardim,+Santo+Andr%C3%A9+-+SP,+09560-105\/@-23.646345,-46.5447722,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce42c3a4c0133d:0xe7c44069a36d82fe!8m2!3d-23.646345!4d-46.5421973!16s%2Fg%2F11c4pjw8xb?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Alameda S\u00e3o Caetano, 395 &#8211; Jardim<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-34306b6\" data-id=\"34306b6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-92209a9\" data-id=\"92209a9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d1e4c75 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"d1e4c75\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/macax1-1.png\" alt=\"macax1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/macax3.png\" alt=\"macax3\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/macax2.png\" alt=\"macax2\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-134c1ca elementor-widget elementor-widget-heading\" data-id=\"134c1ca\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Fazenda Macaxeira<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30291be elementor-widget elementor-widget-text-editor\" data-id=\"30291be\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.facebook.com\/fazendamacaxeirasantoandre?locale=pt_BR\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.instagram.com\/fazendamacaxeira\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/linktr.ee\/fazendamacaxeira\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bb98ad elementor-widget elementor-widget-text-editor\" data-id=\"4bb98ad\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Fazenda+Macaxeira:+Comida+Brasileira,+Executivos,+Chopp,+Cerveja,+Sobremesas,+SP\/@-23.6670271,-46.5348239,15z\/data=!4m6!3m5!1s0x94ce436d8042044d:0xad16c5b62b2fd489!8m2!3d-23.6670271!4d-46.5348239!16s%2Fg%2F11sdq4k1f9?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Av. Portugal, 1313 &#8211; Centro<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-fc6460c\" data-id=\"fc6460c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-0be5d1b\" data-id=\"0be5d1b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fc9bf7b elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"fc9bf7b\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/fonte1-768x432.jpg\" alt=\"fonte1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/fonte2-768x432.jpg\" alt=\"fonte2\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/fonte3-768x432.jpg\" alt=\"fonte3\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/fonte-1-768x432.jpg\" alt=\"fonte\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2913afb elementor-widget elementor-widget-heading\" data-id=\"2913afb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Fonte Leone<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-268609e elementor-widget elementor-widget-text-editor\" data-id=\"268609e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.facebook.com\/fonteleonebar\/?ref=page_internal&amp;locale=pt_BR\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.instagram.com\/fonteleone\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"http:\/\/fonteleonebar.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4c68fd elementor-widget elementor-widget-text-editor\" data-id=\"e4c68fd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Fonte+Leone\/@-23.6481632,-46.5426712,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce56c794c21d47:0x6f86e9f2d7ffc95b!8m2!3d-23.6481681!4d-46.5400963!16s%2Fg%2F1v470gpx?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Rua das Figueiras, 1050 &#8211; Jardim<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3f5dca7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f5dca7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-25a4c99\" data-id=\"25a4c99\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a5309fa elementor-widget elementor-widget-spacer\" data-id=\"a5309fa\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5d7ef9e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5d7ef9e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-7dd687c\" data-id=\"7dd687c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f271118 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"f271118\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/cc510f09-0393-46f4-b198-539768350e42.jpg\" alt=\"cc510f09-0393-46f4-b198-539768350e42\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/deb95a55-66c4-473b-ae4d-ded8be153ceb.jpg\" alt=\"deb95a55-66c4-473b-ae4d-ded8be153ceb\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/Fachada-024-Edit-scaled.jpg\" alt=\"Fachada - 024-Edit\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/11\/231010-Espaco-Kids-008-scaled.jpg\" alt=\"231010 - Espa\u00e7o Kids - 008\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/11\/250129-Rodizio-Noite-02-002-scaled.jpg\" alt=\"250129 - Rodizio Noite 02 - 002\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/11\/Buffet-Executivo-16-1-scaled.jpg\" alt=\"Buffet Executivo (16) (1)\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/11\/Espaco-2-scaled.jpg\" alt=\"Espa\u00e7o (2)\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/11\/Moqueca-de-Peixe-2-scaled.jpg\" alt=\"Moqueca de Peixe (2)\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/11\/Paella-4-scaled.jpg\" alt=\"Paella (4)\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/11\/Patinha-de-Caranguejo-Crocante-3-scaled.jpg\" alt=\"Patinha de Caranguejo Crocante (3)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57648db elementor-widget elementor-widget-heading\" data-id=\"57648db\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Garoupa Frutos do Mar<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30715b2 elementor-widget elementor-widget-text-editor\" data-id=\"30715b2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.instagram.com\/garoupafrutosdomar\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a href=\"https:\/\/www.garoupafrutosdomar.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-232c408 elementor-widget elementor-widget-text-editor\" data-id=\"232c408\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/maps.app.goo.gl\/z5cUkoV927QMb2bu9\"><img loading=\"lazy\" class=\"alignnone\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><br \/><b>Alameda Campestre, 234 &#8211; Bairro Jardim<\/b><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-a0dd51d\" data-id=\"a0dd51d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-44a5ab9\" data-id=\"44a5ab9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-435c122 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"435c122\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/gendai.png\" alt=\"gendai\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/gendai-1-e1710884637736.png\" alt=\"gendai\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ccba8c9 elementor-widget elementor-widget-heading\" data-id=\"ccba8c9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Gendai Culin\u00e1ria Japonesa<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce1f524 elementor-widget elementor-widget-text-editor\" data-id=\"ce1f524\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/gendaioficial\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/gendaioficial\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a href=\"https:\/\/www.gendai.com.br\/home\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f0b305 elementor-widget elementor-widget-text-editor\" data-id=\"3f0b305\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Grand+Plaza+Shopping\/@-23.6487368,-46.5346137,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce4294ff676307:0xd9bb1a8238ff865a!8m2!3d-23.6487368!4d-46.5320388!16s%2Fg%2F120l7rzg?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Av. Industrial, 600 &#8211; Centro &#8211; Grand Plaza Shopping<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-3085beb\" data-id=\"3085beb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-f914a39\" data-id=\"f914a39\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b7bd13 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"2b7bd13\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/Feed-\u2013-4-768x432.png\" alt=\"Feed \u2013 4\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/Instagram-Story-\u2013-5-768x432.png\" alt=\"Instagram Story \u2013 5\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-912881a elementor-widget elementor-widget-heading\" data-id=\"912881a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Gendai Shopping ABC<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35d1b2e elementor-widget elementor-widget-text-editor\" data-id=\"35d1b2e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.facebook.com\/gendaiabc\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.instagram.com\/explore\/locations\/100517442782443\/gendai-shopping-abc\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.gendai.com.br\/home\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-feda30d elementor-widget elementor-widget-text-editor\" data-id=\"feda30d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/maps.app.goo.gl\/YccNsMuiL4Updnhm6\"><img loading=\"lazy\" class=\"alignnone\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><br \/><b>Avenida Pereira Barreto, 42 &#8211; Bairro Para\u00edso &#8211; Shopping ABC<\/b><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-83479e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"83479e1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e5fad85\" data-id=\"e5fad85\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79e8b21 elementor-widget elementor-widget-spacer\" data-id=\"79e8b21\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a7e056 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5a7e056\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-8718ce2\" data-id=\"8718ce2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-690b48b elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"690b48b\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/ital1.jpg\" alt=\"ital1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/ital4.png\" alt=\"ital4\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/ital.jpg\" alt=\"ital\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48436c9 elementor-widget elementor-widget-heading\" data-id=\"48436c9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Ital'in House<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a9c040 elementor-widget elementor-widget-text-editor\" data-id=\"3a9c040\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.facebook.com\/italinhouse\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.instagram.com\/italinhouse.stoandrecampestre\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/italinhouse.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a0b15c0 elementor-widget elementor-widget-text-editor\" data-id=\"a0b15c0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/ITAL'IN+HOUSE+SANTO+ANDR%C3%89+-+CAMPESTRE\/@-23.6518624,-46.5578174,13z\/data=!4m10!1m2!2m1!1sITAL'IN+HOUSE+SANTO+ANDR%C3%89+-+CAMPES!3m6!1s0x94ce43eb0bbabb2f:0x7d36b691756a4b3c!8m2!3d-23.6381697!4d-46.5434552!15sCiNJVEFMJ0lOIEhPVVNFIFNBTlRPIEFORFLDiSAtIENBTVBFU1ojIiFpdGFsIGluIGhvdXNlIHNhbnRvIGFuZHLDqSBjYW1wZXOSARJpdGFsaWFuX3Jlc3RhdXJhbnTgAQA!16s%2Fg%2F11vbgsz8fr?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br><strong>Rua Marina, 316 &#8211; Campestre<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-375ab1c\" data-id=\"375ab1c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-f9437fe\" data-id=\"f9437fe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f0f0d5e elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"f0f0d5e\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/8398e3a7-a621-400b-94e0-67a46b14a395-1.jpg\" alt=\"8398e3a7-a621-400b-94e0-67a46b14a395\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/a0937331-d70b-480c-9fa8-7c57c4e02583-1-768x432.jpg\" alt=\"a0937331-d70b-480c-9fa8-7c57c4e02583\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2857709 elementor-widget elementor-widget-heading\" data-id=\"2857709\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Jardim da Dalva<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cec0d47 elementor-widget elementor-widget-text-editor\" data-id=\"cec0d47\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.instagram.com\/jardim_dadalva\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dae234c elementor-widget elementor-widget-text-editor\" data-id=\"dae234c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/maps.app.goo.gl\/gg4M1Yjwj3SQ8zKdA\"><img loading=\"lazy\" class=\"alignnone\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><br \/><strong><span style=\"color: #1f1f1f; font-family: Arial, sans-serif; font-size: 14px; font-style: normal; text-align: start;\">Rua das Goiabeiras, 807 &#8211; Jardim<\/span><\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-3f09695\" data-id=\"3f09695\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-1a7b46c\" data-id=\"1a7b46c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-530996e elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"530996e\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/05\/jardim.png\" alt=\"jardim\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/05\/jardim3.png\" alt=\"jardim3\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/05\/jardim1.png\" alt=\"jardim1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/05\/jardim4-768x432.png\" alt=\"jardim4\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a9af4e elementor-widget elementor-widget-heading\" data-id=\"3a9af4e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Jardim Secreto<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13f050f elementor-widget elementor-widget-text-editor\" data-id=\"13f050f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.facebook.com\/abc.jardimsecreto\/?locale=pt_BR\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.instagram.com\/jardimsecreto_abc\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c0fd44 elementor-widget elementor-widget-text-editor\" data-id=\"0c0fd44\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Av.+Padre+Manuel+da+N%C3%B3brega,+382+-+Jardim,+Santo+Andr%C3%A9+-+SP,+09080-140\/@-23.6522915,-46.5375869,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce429350415261:0x1a036dbc96a93090!8m2!3d-23.6522915!4d-46.535012!16s%2Fg%2F11c17dczz5?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Av. Pe. Manoel da N\u00f3brega, 382 &#8211; Jardim<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-023df04 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"023df04\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-efcf375\" data-id=\"efcf375\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b8aece7 elementor-widget elementor-widget-spacer\" data-id=\"b8aece7\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c7a3f95 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c7a3f95\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-4b82ee0\" data-id=\"4b82ee0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42cefaa elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"42cefaa\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/jb1.png\" alt=\"jb1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/jb2.png\" alt=\"jb2\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/jb3.png\" alt=\"jb3\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/jb.png\" alt=\"jb\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce0f198 elementor-widget elementor-widget-heading\" data-id=\"ce0f198\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Jb Prime Steak<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dfba28a elementor-widget elementor-widget-text-editor\" data-id=\"dfba28a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/jbprimesteak\/?locale=pt_BR\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/jbprimesteak\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ffd689d elementor-widget elementor-widget-text-editor\" data-id=\"ffd689d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/JB+Prime+Steak+Restaurante\/@-23.6778967,-46.5189926,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce69dff7b00001:0xde2d887c8042f4f0!8m2!3d-23.6778967!4d-46.5164177!16s%2Fg%2F11d_yc_nrw?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Rua das Hort\u00eancias, 154 &#8211; Vila Helena\u00a0<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-535e2e1\" data-id=\"535e2e1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-e9a9c7c\" data-id=\"e9a9c7c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-433adbe elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"433adbe\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/kari3-768x432.jpg\" alt=\"kari3\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/kari-768x432.jpg\" alt=\"kari\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/kari1-768x432.jpg\" alt=\"kari1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/kari2.jpg\" alt=\"kari2\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cd5b64c elementor-widget elementor-widget-heading\" data-id=\"cd5b64c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Kariyushi<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f98d98 elementor-widget elementor-widget-text-editor\" data-id=\"4f98d98\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.facebook.com\/Kariyushisushi?locale=pt_BR\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.instagram.com\/kariyushi_sushi\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/linktr.ee\/kariyushi\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c32e248 elementor-widget elementor-widget-text-editor\" data-id=\"c32e248\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/KARIYUSHI\/@-23.6517727,-46.5372859,17z\/data=!3m2!4b1!5s0x94ce42935894daa7:0xbdf0698ee6f20340!4m6!3m5!1s0x94ce4294ecbc695b:0x4c8b81631dbc8dca!8m2!3d-23.6517776!4d-46.534711!16s%2Fg%2F11b6gcx6qs?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Rua das Esmeraldas, 271 &#8211; Jardim<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-6ba3a9a\" data-id=\"6ba3a9a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-e1bf2f2\" data-id=\"e1bf2f2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d1bc505 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"d1bc505\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/king.png\" alt=\"king\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/king1.png\" alt=\"king1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/king2.png\" alt=\"king2\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/king3.png\" alt=\"king3\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cdce81f elementor-widget elementor-widget-heading\" data-id=\"cdce81f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">King Sushi<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-475396b elementor-widget elementor-widget-text-editor\" data-id=\"475396b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/restaurantekingsushi\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/restaurantekingsushi\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a href=\"https:\/\/www.kingsushi.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a8d0bc elementor-widget elementor-widget-text-editor\" data-id=\"6a8d0bc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps?sca_esv=5d0811d5ae0715ef&amp;rlz=1C1GCEU_pt-BRBR1098BR1098&amp;output=search&amp;q=Alameda+S%C3%A3o+Caetano,+374&amp;source=lnms&amp;entry=mc&amp;ved=1t:200715&amp;ictx=111\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Alameda S\u00e3o Caetano, 374 &#8211; Jardim<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c6f8836 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c6f8836\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-61f4d01\" data-id=\"61f4d01\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d57ab2a elementor-widget elementor-widget-spacer\" data-id=\"d57ab2a\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-62590bb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"62590bb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-86f3a43\" data-id=\"86f3a43\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f821ab elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"6f821ab\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/b4477180-e0f7-44a6-a254-e9c79fa278cb.jpg\" alt=\"b4477180-e0f7-44a6-a254-e9c79fa278cb\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/11\/IMG_2143-1-1.png\" alt=\"IMG_2143 (1)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0752ffd elementor-widget elementor-widget-heading\" data-id=\"0752ffd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">La Cantina - Cucina Italiana <\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a5aa5f9 elementor-widget elementor-widget-text-editor\" data-id=\"a5aa5f9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/p\/La-Cantina-Cucina-Italiana-100082980080134\/?locale=pt_BR\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/lacantina_cucinaitaliana\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a href=\"https:\/\/www.restaurantelacantina.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15a3056 elementor-widget elementor-widget-text-editor\" data-id=\"15a3056\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/maps.app.goo.gl\/tS1RtJ3y9Qsaggpi9\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Rua Padre Manoel de Paiva, 66 &#8211; Jardim<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-2db1b06\" data-id=\"2db1b06\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-ec4e705\" data-id=\"ec4e705\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17141c4 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"17141c4\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/Manduu.jpg\" alt=\"Manduu\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/manduu1.png\" alt=\"manduu1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/manduu3.png\" alt=\"manduu3\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ab3f58 elementor-widget elementor-widget-heading\" data-id=\"3ab3f58\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Manduu<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e84716 elementor-widget elementor-widget-text-editor\" data-id=\"9e84716\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/espacomanduu\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/espaco_manduu\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a href=\"https:\/\/manduu.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c62204c elementor-widget elementor-widget-text-editor\" data-id=\"c62204c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Espa%C3%A7o+Manduu\/@-23.6538677,-46.5372733,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce436030c0e631:0x758bb6223278bcf1!8m2!3d-23.6538677!4d-46.5346984!16s%2Fg%2F11fld1584r?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Rua das Bandeiras, 266 &#8211; Jardim<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-e27558e\" data-id=\"e27558e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-c03ec06\" data-id=\"c03ec06\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e21ff3 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"4e21ff3\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/a626544f-1516-4876-b797-4046c11c8381-768x432.jpg\" alt=\"a626544f-1516-4876-b797-4046c11c8381\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/c686f657-a241-414c-87be-18b5d8f64866-768x432.jpg\" alt=\"c686f657-a241-414c-87be-18b5d8f64866\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/Fachada-Maoboa-768x432.png\" alt=\"Fachada Maobo\u00e1\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aba1e04 elementor-widget elementor-widget-heading\" data-id=\"aba1e04\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Mao Boa<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f29d96c elementor-widget elementor-widget-text-editor\" data-id=\"f29d96c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/restaurantemaoboa\/?locale=pt_BR\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/maoboarestaurante\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a0093a2 elementor-widget elementor-widget-text-editor\" data-id=\"a0093a2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/maps.app.goo.gl\/3DEReDeSM6jV4y7v9\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Avenida dos Andradas, 447 &#8211; Vila Assun\u00e7\u00e3o<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-72e5946 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"72e5946\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c143f23\" data-id=\"c143f23\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40f55de elementor-widget elementor-widget-spacer\" data-id=\"40f55de\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-82e6338 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"82e6338\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-8fac1b9\" data-id=\"8fac1b9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f77dc6b elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"f77dc6b\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/mei.png\" alt=\"mei\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/mei1.png\" alt=\"mei1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/mei2.png\" alt=\"mei2\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da59334 elementor-widget elementor-widget-heading\" data-id=\"da59334\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Mei Mei Culin\u00e1ria Asi\u00e1tica<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-773ce66 elementor-widget elementor-widget-text-editor\" data-id=\"773ce66\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.instagram.com\/meimei.oficial\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a href=\"https:\/\/www.meimeifood.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0674d38 elementor-widget elementor-widget-text-editor\" data-id=\"0674d38\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Grand+Plaza+Shopping\/@-23.6487368,-46.5346137,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce4294ff676307:0xd9bb1a8238ff865a!8m2!3d-23.6487368!4d-46.5320388!16s%2Fg%2F120l7rzg?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Av. Industrial, 600 &#8211; Centro &#8211; Grand Plaza Shopping<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-7e9410f\" data-id=\"7e9410f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-b337340\" data-id=\"b337340\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c8db9d elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"4c8db9d\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/Mia-768x432.jpg\" alt=\"Mia\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/mia3.png\" alt=\"mia3\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/mia1.png\" alt=\"mia1\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff77ab8 elementor-widget elementor-widget-heading\" data-id=\"ff77ab8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Mia Cuccina<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-030d679 elementor-widget elementor-widget-text-editor\" data-id=\"030d679\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/profile.php?id=100093466495295\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/espaco_miacucina\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a href=\"https:\/\/www.restaurantemiacucina.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f886ded elementor-widget elementor-widget-text-editor\" data-id=\"f886ded\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Mia+Cucina\/@-23.6461962,-46.542633,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce433741320aa9:0xd704adb5871c7946!8m2!3d-23.6462011!4d-46.5400581!16s%2Fg%2F11jsrnd3d7?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Rua das Paineiras, 520 &#8211; Jardim<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-d6c4226\" data-id=\"d6c4226\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-1942562\" data-id=\"1942562\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1fd51ee elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"1fd51ee\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/mont3-1.png\" alt=\"mont3\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/mont-2-768x432.png\" alt=\"mont\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/mont1-1.png\" alt=\"mont1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/mont4-1.png\" alt=\"mont4\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a29924 elementor-widget elementor-widget-heading\" data-id=\"5a29924\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Mont Cristo Wine &amp; Bar<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2570f68 elementor-widget elementor-widget-text-editor\" data-id=\"2570f68\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.instagram.com\/montcristowinebar\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.montcristowinebar.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b94ca3 elementor-widget elementor-widget-text-editor\" data-id=\"0b94ca3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Mont+Cristo+Wine+%26+Bar\/@-23.651833,-46.5409765,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce43caef534bad:0x3c052152ec896fb2!8m2!3d-23.651833!4d-46.5384016!16s%2Fg%2F11rz9ck0bn?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Rua das Figueiras, 631 &#8211; Jardim<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f9a0d1c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f9a0d1c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f9135d5\" data-id=\"f9135d5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-946098f elementor-widget elementor-widget-spacer\" data-id=\"946098f\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e5b904e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e5b904e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-e8f8fd6\" data-id=\"e8f8fd6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-94b7553 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"94b7553\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/mundo2.png\" alt=\"mundo2\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/mundo-1.png\" alt=\"mundo\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/mundo5.png\" alt=\"mundo5\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/mundo-2-768x432.png\" alt=\"mundo\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b09c3c0 elementor-widget elementor-widget-heading\" data-id=\"b09c3c0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Mundo Animal Lanchonete Tem\u00e1tica<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79fcd97 elementor-widget elementor-widget-text-editor\" data-id=\"79fcd97\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/euamomundoanimalsantoandre\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/euamomundoanimal\/?hl=pt-br\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a href=\"https:\/\/www.euamomundoanimal.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d8a2a9 elementor-widget elementor-widget-text-editor\" data-id=\"3d8a2a9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Mundo+Animal+Lanchonete+Tem%C3%A1tica+Santo+Andr%C3%A9+-+Comidas+e+Bebidas\/@-23.6230163,-46.5415983,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce5dd92b74cadf:0x85cf7b67a272058e!8m2!3d-23.6230163!4d-46.5390234!16s%2Fg%2F11s0g7vpk3?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Rua Berlim, 243 &#8211; Utinga<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-e6715ab\" data-id=\"e6715ab\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-77a89c8\" data-id=\"77a89c8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d42e483 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"d42e483\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/1aa5ab65-92ea-4ad1-86f6-80485c51d25f-768x432.jpg\" alt=\"1aa5ab65-92ea-4ad1-86f6-80485c51d25f\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/e10e2563-ecbb-4e62-bbe5-ccbd6108f18c-768x432.jpg\" alt=\"e10e2563-ecbb-4e62-bbe5-ccbd6108f18c\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d9e001 elementor-widget elementor-widget-heading\" data-id=\"2d9e001\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Okazaki Sushi\n<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c7b9a6 elementor-widget elementor-widget-text-editor\" data-id=\"1c7b9a6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/people\/Okazaki-Sushi\/100092498918173\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/okazaki.sushi\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a href=\"https:\/\/www.okazakisushi.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3e0617 elementor-widget elementor-widget-text-editor\" data-id=\"e3e0617\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/maps.app.goo.gl\/mvB57LVF7kBoknwn9\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Avenida Padre Anchieta, 234 &#8211; Jardim\u00a0<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-c7af22c\" data-id=\"c7af22c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-a5df289\" data-id=\"a5df289\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0249890 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"0249890\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/out.jpg\" alt=\"out\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/out1.jpg\" alt=\"out1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/out2.jpg\" alt=\"out2\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/out4-768x432.jpg\" alt=\"out4\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c41b216 elementor-widget elementor-widget-heading\" data-id=\"c41b216\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Outback<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45c1c9d elementor-widget elementor-widget-text-editor\" data-id=\"45c1c9d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.facebook.com\/outbackbrasil\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.instagram.com\/outbackbrasil\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.outback.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69c3c16 elementor-widget elementor-widget-text-editor\" data-id=\"69c3c16\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Grand+Plaza+Shopping\/@-23.6487368,-46.5346137,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce4294ff676307:0xd9bb1a8238ff865a!8m2!3d-23.6487368!4d-46.5320388!16s%2Fg%2F120l7rzg?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Av. Industrial, 600 &#8211; Centro &#8211; Grand Plaza Shopping<br \/><\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ccad2b7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ccad2b7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7862dcd\" data-id=\"7862dcd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-446de8e elementor-widget elementor-widget-spacer\" data-id=\"446de8e\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1ff5c84 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1ff5c84\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-f16bbc3\" data-id=\"f16bbc3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b82493c elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"b82493c\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/tai-chi-1-1.jpg\" alt=\"tai chi 1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/tai-chi-2.jpg\" alt=\"tai chi\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/tai-chi2-768x431.png\" alt=\"tai chi2\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a1c616 elementor-widget elementor-widget-heading\" data-id=\"0a1c616\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Pal\u00e1cio Tai Chi<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f99d7b elementor-widget elementor-widget-text-editor\" data-id=\"3f99d7b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.facebook.com\/RestaurantePalacioTaiChi\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.instagram.com\/restaurante_palaciotaichi\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9087dc5 elementor-widget elementor-widget-text-editor\" data-id=\"9087dc5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/maps.app.goo.gl\/DZUQGCXSCcDZ3Dqz5\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Av. Artur de Queir\u00f3s, 112 &#8211; Casa Branca<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-e07f561\" data-id=\"e07f561\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-10d9ba8\" data-id=\"10d9ba8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b84612 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"6b84612\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/parrila2.png\" alt=\"parrila2\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/parrila.png\" alt=\"parrila\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/parrila1.png\" alt=\"parrila1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/parrila5.png\" alt=\"parrila5\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04670bc elementor-widget elementor-widget-heading\" data-id=\"04670bc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Parrila Del Carmem<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7b6bde elementor-widget elementor-widget-text-editor\" data-id=\"f7b6bde\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/parrilladelcarmem\/?locale=pt_BR\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/parrilladelcarmem\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a href=\"https:\/\/parrilladelcarmem.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c090d2e elementor-widget elementor-widget-text-editor\" data-id=\"c090d2e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Parrilla+Del+Carmem\/@-23.6483534,-46.5417628,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce42c1e0640001:0x7ad11e2dbf1fcc64!8m2!3d-23.6483534!4d-46.5391879!16s%2Fg%2F11b6hx1077?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Rua das Paineiras, 269 &#8211; Jardim<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-65c8e18\" data-id=\"65c8e18\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-9aee9cf\" data-id=\"9aee9cf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ea034b elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"1ea034b\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/pecorino2.png\" alt=\"pecorino2\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/pecorino.png\" alt=\"pecorino\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/pecorino1.png\" alt=\"pecorino1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/pecorino3.png\" alt=\"pecorino3\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c18f9f0 elementor-widget elementor-widget-heading\" data-id=\"c18f9f0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Pecorino<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba70785 elementor-widget elementor-widget-text-editor\" data-id=\"ba70785\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.instagram.com\/pecorinobr\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a href=\"https:\/\/www.pecorino.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9e72be elementor-widget elementor-widget-text-editor\" data-id=\"d9e72be\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps?sca_esv=f4dacfe81c780abe&amp;sca_upv=1&amp;rlz=1C1GCEU_pt-BRBR1098BR1098&amp;output=search&amp;q=shopping+abc&amp;source=lnms&amp;entry=mc&amp;utm_campaign=srp-cst&amp;ved=1t:200715&amp;ictx=111\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Av. Pereira Barreto, 42 &#8211; Vl. Gilda\u00a0 &#8211; Shopping ABC<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5b1da1c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5b1da1c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-348769e\" data-id=\"348769e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fbd6465 elementor-widget elementor-widget-spacer\" data-id=\"fbd6465\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aa7398a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aa7398a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-bcfd37b\" data-id=\"bcfd37b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ccba5cf elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"ccba5cf\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/05\/panelas.png\" alt=\"panelas\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/05\/panelas1.png\" alt=\"panelas1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/05\/panelas3.png\" alt=\"panelas3\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9bec5d4 elementor-widget elementor-widget-heading\" data-id=\"9bec5d4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Pelas Panelas<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91bcd21 elementor-widget elementor-widget-text-editor\" data-id=\"91bcd21\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.instagram.com\/pelas_panelas\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a href=\"https:\/\/linktr.ee\/PelasPanelas\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a5928ad elementor-widget elementor-widget-text-editor\" data-id=\"a5928ad\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/R.+das+Aroeiras,+490+-+Jardim,+Santo+Andr%C3%A9+-+SP,+09090-000\/@-23.6466124,-46.5441559,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce42c3b607da23:0x2c6437192684e001!8m2!3d-23.6466124!4d-46.541581!16s%2Fg%2F11n2ldgbs6?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Rua das Aroeiras, 490 &#8211; Jardim<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-03b1b00\" data-id=\"03b1b00\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-6d3a7be\" data-id=\"6d3a7be\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69e643d elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"69e643d\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/pilao-768x432.jpg\" alt=\"pil\u00e3o\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/pilao1.jpg\" alt=\"pilao1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/pilao2-768x432.jpg\" alt=\"pilao2\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/pilao-5-768x432.jpg\" alt=\"pil\u00e3o 5\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56dd1f0 elementor-widget elementor-widget-heading\" data-id=\"56dd1f0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Pil\u00e3o Mineiro<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03bc23f elementor-widget elementor-widget-text-editor\" data-id=\"03bc23f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.facebook.com\/PilaoMineiroRestaurante\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.instagram.com\/pilao.mineiro\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/pilaomineiro.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aeac764 elementor-widget elementor-widget-text-editor\" data-id=\"aeac764\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Pil%C3%A3o+Mineiro+Restaurante\/@-23.6457232,-46.5402024,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce42c05411ac4f:0x1f1857eaf6918d4b!8m2!3d-23.6457281!4d-46.5376275!16s%2Fg%2F1tlgz1pq?authuser=0&amp;hl=pt-BR&amp;entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Av. Dom Pedro II, 1172 &#8211; Jardim<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-4ad548a\" data-id=\"4ad548a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-1b68a5c\" data-id=\"1b68a5c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f218573 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"f218573\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/39e39bff-84af-4f54-adf7-f0faf40ae7bf-768x432.jpg\" alt=\"39e39bff-84af-4f54-adf7-f0faf40ae7bf\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/cf51b4c5-1857-4c16-b35e-3fc4f21679bf.jpg\" alt=\"cf51b4c5-1857-4c16-b35e-3fc4f21679bf\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2bf649 elementor-widget elementor-widget-heading\" data-id=\"a2bf649\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Point Bar<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03e636a elementor-widget elementor-widget-text-editor\" data-id=\"03e636a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.instagram.com\/pointbarabc\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/linktr.ee\/pointbarabc\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4456c8 elementor-widget elementor-widget-text-editor\" data-id=\"e4456c8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/maps.app.goo.gl\/ebR8tNBGNBb54W6QA\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Rua Santo Urb\u00e2no, 115 &#8211; Jardim Bela Vista<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-25605f3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"25605f3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2049685\" data-id=\"2049685\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78762fc elementor-widget elementor-widget-spacer\" data-id=\"78762fc\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3a9b4ac elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3a9b4ac\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-1239398\" data-id=\"1239398\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-940bff8 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"940bff8\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/39e39bff-84af-4f54-adf7-f0faf40ae7bf-1-768x432.jpg\" alt=\"39e39bff-84af-4f54-adf7-f0faf40ae7bf\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/IMG_0767-768x432.jpeg\" alt=\"IMG_0767\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/IMG_5191-768x432.jpg\" alt=\"IMG_5191\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c24ff1 elementor-widget elementor-widget-heading\" data-id=\"0c24ff1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Point do Gord\u00e3o - Na\u00e7\u00f5es <\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea816e4 elementor-widget elementor-widget-text-editor\" data-id=\"ea816e4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.instagram.com\/pointdogordaosp\/?hl=pt-br\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a href=\"https:\/\/linktr.ee\/pointdogordaosp\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff91719 elementor-widget elementor-widget-text-editor\" data-id=\"ff91719\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/maps.app.goo.gl\/MgHJ2psZHLTxT6x68\"><img loading=\"lazy\" class=\"alignnone\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><br \/><span style=\"color: #1f1f1f; font-family: Arial, sans-serif; font-size: 14px; font-style: normal; text-align: start;\"><b>Avenida das Na\u00e7\u00f5es, 2030 &#8211; Parque Novo Orat\u00f3rio<\/b><\/span><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-cddd724\" data-id=\"cddd724\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-ca5a4a8\" data-id=\"ca5a4a8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e3ed56 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"3e3ed56\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/IMG_5191-768x432.jpg\" alt=\"IMG_5191\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/IMG_0767-768x432.jpeg\" alt=\"IMG_0767\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/39e39bff-84af-4f54-adf7-f0faf40ae7bf-1-768x432.jpg\" alt=\"39e39bff-84af-4f54-adf7-f0faf40ae7bf\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b792d3 elementor-widget elementor-widget-heading\" data-id=\"6b792d3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Point do Gord\u00e3o - Santa Terezinha<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e36ff2 elementor-widget elementor-widget-text-editor\" data-id=\"6e36ff2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.instagram.com\/pointdogordaosp\/?hl=pt-br\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a href=\"https:\/\/linktr.ee\/pointdogordaosp\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93aaf64 elementor-widget elementor-widget-text-editor\" data-id=\"93aaf64\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/maps.app.goo.gl\/mNPyPvqDSfQkksmL9\"><img loading=\"lazy\" class=\"alignnone\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><br \/><span style=\"color: #1f1f1f; font-family: Arial, sans-serif; font-size: 14px; font-style: normal; text-align: start;\"><b>Alameda Vieira de Carvalho, 336 &#8211; Santa Terezinha<\/b><\/span><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-cfb81af\" data-id=\"cfb81af\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-537640e\" data-id=\"537640e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42f7aca elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"42f7aca\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/porto.png\" alt=\"porto\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/porto5.png\" alt=\"porto5\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/porto3.png\" alt=\"porto3\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/porto4.png\" alt=\"porto4\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/porto2.png\" alt=\"porto2\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b449bf0 elementor-widget elementor-widget-heading\" data-id=\"b449bf0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Portofino<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15f1ab6 elementor-widget elementor-widget-text-editor\" data-id=\"15f1ab6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/PortofinoCucinaItaliana\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/portofinocucinaitaliana\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a href=\"https:\/\/www.portofinocucinaitaliana.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d56b058 elementor-widget elementor-widget-text-editor\" data-id=\"d56b058\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Grand+Plaza+Shopping\/@-23.6487368,-46.5320388,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce4294ff676307:0xd9bb1a8238ff865a!8m2!3d-23.6487368!4d-46.5320388!16s%2Fg%2F120l7rzg?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Av. Industrial, 600 &#8211; Centro &#8211; Grand Plaza Shopping<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-617f881 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"617f881\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f8535b5\" data-id=\"f8535b5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ac01c6 elementor-widget elementor-widget-spacer\" data-id=\"5ac01c6\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6a71fb9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6a71fb9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-9487f2d\" data-id=\"9487f2d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2fcf65f elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"2fcf65f\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/quintal1.png\" alt=\"quintal1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/quintal-5-768x432.jpg\" alt=\"quintal 5\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/quintal-4-768x432.jpg\" alt=\"quintal 4\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/quintal-2-768x432.jpg\" alt=\"quintal 2\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98b44f9 elementor-widget elementor-widget-heading\" data-id=\"98b44f9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Quintal Del Carmem<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-88b42a8 elementor-widget elementor-widget-text-editor\" data-id=\"88b42a8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/quintaldelcarmem\/photos?locale=pt_BR\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/quintaldelcarmem\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aea4757 elementor-widget elementor-widget-text-editor\" data-id=\"aea4757\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Quintal+Del+Carmem\/@-23.6486835,-46.5414352,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce43fce75f74d3:0x37671eb2cd4a332c!8m2!3d-23.6486835!4d-46.5388603!16s%2Fg%2F11nx69bv_1?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Rua das Paineiras, 243 &#8211; Jardim<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-7fa8b15\" data-id=\"7fa8b15\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-3640b05\" data-id=\"3640b05\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f9d644 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"6f9d644\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/Foto-cerveja-1-768x432.jpg\" alt=\"Foto-cerveja (1)\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/Quintal-do-espeto-Unidade-Santo-Andre-1-768x432.jpg\" alt=\"Quintal-do-espeto-Unidade-Santo-Andr\u00e9 (1)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-89811fa elementor-widget elementor-widget-heading\" data-id=\"89811fa\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Quintal do Espeto<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-338e6fb elementor-widget elementor-widget-text-editor\" data-id=\"338e6fb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.facebook.com\/quintaldoespetooficial\/?locale=pt_BR\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.instagram.com\/quintalsantoandre\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/quintaldoespeto.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec31ccc elementor-widget elementor-widget-text-editor\" data-id=\"ec31ccc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/maps.app.goo.gl\/oYzpLR9a9nwaMA9v5\"><img loading=\"lazy\" class=\"alignnone\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><br \/><strong><span style=\"color: #1f1f1f; font-family: Arial, sans-serif; font-size: 14px; font-style: normal; text-align: start;\">Rua das Figueiras, 420 &#8211; Jardim<\/span><\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-fd98ec2\" data-id=\"fd98ec2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-1e26b41\" data-id=\"1e26b41\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47bc714 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"47bc714\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/ramos.jpg\" alt=\"ramos\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/ramos1.jpg\" alt=\"ramos1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/ramos2-768x432.jpg\" alt=\"ramos2\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a4f341f elementor-widget elementor-widget-heading\" data-id=\"a4f341f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Ramos Frutos do Mar<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-815756c elementor-widget elementor-widget-text-editor\" data-id=\"815756c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.facebook.com\/ramosfrutosdomar\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.instagram.com\/ramosfrutosdomar\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"http:\/\/www.ramosfrutosdomar.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fda0e3b elementor-widget elementor-widget-text-editor\" data-id=\"fda0e3b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Ramos+Frutos+do+Mar\/@-23.6531142,-46.5148967,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce684d2e2db343:0x2b0f757347e5f315!8m2!3d-23.6531192!4d-46.5100258!16s%2Fg%2F1tlbvvrq?authuser=0&amp;hl=pt-BR&amp;entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Av. dos Estados, 2195 &#8211; Vila Metalurgica &#8211; Ceasa Grande ABC<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6234712 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6234712\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4fa3184\" data-id=\"4fa3184\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-efb7878 elementor-widget elementor-widget-spacer\" data-id=\"efb7878\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-705c2f3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"705c2f3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-3b47d2e\" data-id=\"3b47d2e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-168b671 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"168b671\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/8d6d6fd7-04bd-48c7-be6d-6ddf5c8bbec0-768x432.jpg\" alt=\"8d6d6fd7-04bd-48c7-be6d-6ddf5c8bbec0\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/096b3e27-ab1b-465b-90a7-ba7bba996e80-768x432.jpg\" alt=\"096b3e27-ab1b-465b-90a7-ba7bba996e80\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/a06b95cf-da0b-43ed-b35a-0e86e27e5e66-768x432.jpg\" alt=\"a06b95cf-da0b-43ed-b35a-0e86e27e5e66\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/de9bc614-cbf8-4292-ab92-3d4ac89ca3d3-768x432.jpg\" alt=\"de9bc614-cbf8-4292-ab92-3d4ac89ca3d3\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b8d6bb2 elementor-widget elementor-widget-heading\" data-id=\"b8d6bb2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Rancho dos Peruanos<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-193de36 elementor-widget elementor-widget-text-editor\" data-id=\"193de36\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.facebook.com\/RanchoDosPeruanos\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.instagram.com\/ranchodosperuanosabc\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/ranchodosperuanos.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b99297 elementor-widget elementor-widget-text-editor\" data-id=\"1b99297\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/maps.app.goo.gl\/gKnt8qPbHyV4NpAA7\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><b>Rua Edu Chaves, 8 &#8211; Jardim Bela Vista<\/b><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-ec3fbdf\" data-id=\"ec3fbdf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-8e5b902\" data-id=\"8e5b902\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f65af44 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"f65af44\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/rosas3-1.jpg\" alt=\"rosas3\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/rosas5-768x432.jpg\" alt=\"rosas5\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/rosas-768x432.jpg\" alt=\"rosas\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/rosas1-768x432.jpg\" alt=\"rosas1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/rosas2-768x432.jpg\" alt=\"rosas2\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-578df70 elementor-widget elementor-widget-heading\" data-id=\"578df70\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Rosa's Churrascaria<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bafe2fd elementor-widget elementor-widget-text-editor\" data-id=\"bafe2fd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.facebook.com\/rosaschurrascariaoficial\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.instagram.com\/rosaschurrascaria\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.rosaschurrascaria.com.br\/index.html\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ed248c elementor-widget elementor-widget-text-editor\" data-id=\"8ed248c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Rosa's+Churrascaria\/@-23.6675461,-46.5186933,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce69d7d8431b95:0x94911ebe81805f10!8m2!3d-23.667551!4d-46.5161184!16s%2Fg%2F11b6g99w9p?authuser=0&amp;hl=pt-BR&amp;entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Rua Natal, 285 &#8211; Silveira<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-d503ea9\" data-id=\"d503ea9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-8909f9d\" data-id=\"8909f9d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d6eda9f elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"d6eda9f\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/si.png\" alt=\"si\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/si1.png\" alt=\"si1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/si2.png\" alt=\"si2\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/tex-1.png\" alt=\"tex\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a048a1 elementor-widget elementor-widget-text-editor\" data-id=\"0a048a1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><span style=\"color: #000000;\">Si Se\u00f1or! Tex-Mex<\/span><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c9ad924 elementor-widget elementor-widget-text-editor\" data-id=\"c9ad924\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.facebook.com\/sisenorbrasil\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" data-wp-editing=\"1\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.instagram.com\/sisenorbrasil\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.sisenor.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c6eede elementor-widget elementor-widget-text-editor\" data-id=\"3c6eede\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/S%C3%AD+Se%C3%B1or\/@-23.6475225,-46.5431534,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce42c224045c69:0x9058b4e7124493c9!8m2!3d-23.6475274!4d-46.5405785!16s%2Fg%2F1tdq27mb?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Rua das Caneleiras, 555 &#8211; Jardim<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9e66fd6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9e66fd6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-35f816c\" data-id=\"35f816c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b754ce0 elementor-widget elementor-widget-spacer\" data-id=\"b754ce0\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9e4beb5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9e4beb5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-bc1d56f\" data-id=\"bc1d56f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7918693 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"7918693\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/sky.png\" alt=\"sky\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/sky1.png\" alt=\"sky1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/sky2.png\" alt=\"sky2\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed04a8e elementor-widget elementor-widget-heading\" data-id=\"ed04a8e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Sky Asia<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ae11e9 elementor-widget elementor-widget-text-editor\" data-id=\"7ae11e9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/pages\/Sky-Asia\/633105807080154\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/skyasiasp\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a href=\"http:\/\/www.skyasia.com.br\/cardapio.html\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bbce99d elementor-widget elementor-widget-text-editor\" data-id=\"bbce99d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Grand+Plaza+Shopping\/@-23.6487368,-46.5346137,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce4294ff676307:0xd9bb1a8238ff865a!8m2!3d-23.6487368!4d-46.5320388!16s%2Fg%2F120l7rzg?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Av. Industrial, 600 &#8211; Centro &#8211; Grand Plaza Shopping<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-92ffe75\" data-id=\"92ffe75\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-3a9344f\" data-id=\"3a9344f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cdb6783 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"cdb6783\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/05\/bella2.png\" alt=\"bella2\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/05\/bella1.png\" alt=\"bella1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/05\/bella.png\" alt=\"bella\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/05\/bella4.png\" alt=\"bella4\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8fb5ad6 elementor-widget elementor-widget-heading\" data-id=\"8fb5ad6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Spazio Bella<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55a597d elementor-widget elementor-widget-text-editor\" data-id=\"55a597d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.facebook.com\/SpazioBellaSantoAndreSP\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.instagram.com\/spaziobellasantoandre\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.spaziobellarestaurante.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff06c88 elementor-widget elementor-widget-text-editor\" data-id=\"ff06c88\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps?sca_esv=de93c5c4281f23a7&amp;sca_upv=1&amp;rlz=1C1GCEU_pt-BRBR1098BR1098&amp;output=search&amp;q=Rua+Giovanni+Battista+Pirelli,+279+-+Vila+Homero+Thon,&amp;source=lnms&amp;entry=mc&amp;ved=1t:200715&amp;ictx=111\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Rua Giovanni Battista Pirelli, 279 &#8211; Vila Homero Thon &#8211; Hotel Hilton Garden Inn<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-4f65f6c\" data-id=\"4f65f6c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-a6344fc\" data-id=\"a6344fc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e432a5c elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"e432a5c\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/spazio.jpg\" alt=\"spazio\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/spazio4.png\" alt=\"spazio4\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/spzio1.png\" alt=\"spzio1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/spazio2.png\" alt=\"spazio2\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-209372d elementor-widget elementor-widget-heading\" data-id=\"209372d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Spazio Santo Disco<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25bffd3 elementor-widget elementor-widget-text-editor\" data-id=\"25bffd3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.facebook.com\/spaziosantodisco\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.instagram.com\/spaziosantodisco\/?hl=pt\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/spaziosantodisco.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-86cea1b elementor-widget elementor-widget-text-editor\" data-id=\"86cea1b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Spazio+Santo+Disco+Restaurante+%26+Pizzaria\/@-23.6750858,-46.5253781,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce43b6b31fb09d:0x845757603a3ff8fe!8m2!3d-23.6750907!4d-46.5228032!16s%2Fg%2F11hzzvmk7w?authuser=0&amp;hl=pt-BR&amp;entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Rua Paranapanema, 239 &#8211; Vila Alzira<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d04e6d5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d04e6d5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c5085cd\" data-id=\"c5085cd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f1bb67 elementor-widget elementor-widget-spacer\" data-id=\"2f1bb67\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-db0aa96 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"db0aa96\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-d02a663\" data-id=\"d02a663\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47c1c4d elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"47c1c4d\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/spoleto-768x432.jpg\" alt=\"spoleto\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/spoleto1-768x432.jpg\" alt=\"spoleto1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/spoleto2-768x432.png\" alt=\"spoleto2\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/spoleto3-768x432.jpg\" alt=\"spoleto3\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e046053 elementor-widget elementor-widget-heading\" data-id=\"e046053\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Spoleto<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94ee03d elementor-widget elementor-widget-text-editor\" data-id=\"94ee03d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.facebook.com\/spoleto\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.instagram.com\/spoleto_oficial\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.spoleto.com.br\/tabs\/cardapioapp\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b38bfaa elementor-widget elementor-widget-text-editor\" data-id=\"b38bfaa\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps?sca_esv=f4dacfe81c780abe&amp;sca_upv=1&amp;rlz=1C1GCEU_pt-BRBR1098BR1098&amp;output=search&amp;q=shopping+abc&amp;source=lnms&amp;entry=mc&amp;utm_campaign=srp-cst&amp;ved=1t:200715&amp;ictx=111\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Av. Pereira Barreto, 42 &#8211; Vl. Gilda\u00a0 &#8211; Shopping ABC<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-0026840\" data-id=\"0026840\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-5391e9a\" data-id=\"5391e9a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dc4f198 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"dc4f198\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/spoleto-768x432.jpg\" alt=\"spoleto\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/spoleto1-768x432.jpg\" alt=\"spoleto1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/spoleto2-768x432.png\" alt=\"spoleto2\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/spoleto3-768x432.jpg\" alt=\"spoleto3\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a4082d1 elementor-widget elementor-widget-heading\" data-id=\"a4082d1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Spoleto<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d10f4bf elementor-widget elementor-widget-text-editor\" data-id=\"d10f4bf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.facebook.com\/spoleto\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.instagram.com\/spoleto_oficial?igsh=MTdkdjZ1bHF6aXJqOQ==\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.spoleto.com.br\/tabs\/cardapioapp\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c83380 elementor-widget elementor-widget-text-editor\" data-id=\"1c83380\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Grand+Plaza+Shopping\/@-23.6487368,-46.5320388,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce4294ff676307:0xd9bb1a8238ff865a!8m2!3d-23.6487368!4d-46.5320388!16s%2Fg%2F120l7rzg?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Av. Industrial, 600 &#8211; Centro &#8211; Grand Plaza Shopping<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-ac5884c\" data-id=\"ac5884c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-2cb8dcf\" data-id=\"2cb8dcf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18f425b elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"18f425b\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/8fa557b1-db51-40e6-af90-a83b108b0c99.jpg\" alt=\"8fa557b1-db51-40e6-af90-a83b108b0c99\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/aaab9f8c-8836-4cb8-8477-d00e0b15dcc0-768x432.jpg\" alt=\"aaab9f8c-8836-4cb8-8477-d00e0b15dcc0\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/06\/ea123cdb-f5fe-47c4-8f5d-5f833eb14d11-768x432.jpg\" alt=\"ea123cdb-f5fe-47c4-8f5d-5f833eb14d11\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-500783a elementor-widget elementor-widget-heading\" data-id=\"500783a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Sublime Bistr\u00f4<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6fc8512 elementor-widget elementor-widget-text-editor\" data-id=\"6fc8512\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.facebook.com\/p\/Sublime-Bistr%C3%B4-100070889063857\/?locale=pt_BR\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.instagram.com\/sublime_bistro\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/linktr.ee\/sublimebistro\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48c13e6 elementor-widget elementor-widget-text-editor\" data-id=\"48c13e6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/maps.app.goo.gl\/suUory59qT3dhsE59\"><img loading=\"lazy\" class=\"alignnone\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><br \/><strong><span style=\"color: #1f1f1f; font-family: Arial, sans-serif; font-size: 14px; font-style: normal; text-align: start;\">Rua Uruguaiana, 395 &#8211; Vila Leopoldina<\/span><\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a8d4954 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a8d4954\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a15ed97\" data-id=\"a15ed97\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9f9747b elementor-widget elementor-widget-spacer\" data-id=\"9f9747b\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1993600 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1993600\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-317994b\" data-id=\"317994b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f44272a elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"f44272a\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/super.png\" alt=\"super\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/super1.png\" alt=\"super1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/super2.png\" alt=\"super2\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/super3.png\" alt=\"super3\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20d2f0f elementor-widget elementor-widget-heading\" data-id=\"20d2f0f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Super Grill Express<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2f762d elementor-widget elementor-widget-text-editor\" data-id=\"c2f762d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/supergrillsp\/?locale=pt_BR\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/supergrillsp.oficial\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a href=\"https:\/\/www.supergrillexpress.com.br\/santoandre.html\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dde8bf9 elementor-widget elementor-widget-text-editor\" data-id=\"dde8bf9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Grand+Plaza+Shopping\/@-23.6487368,-46.5346137,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce4294ff676307:0xd9bb1a8238ff865a!8m2!3d-23.6487368!4d-46.5320388!16s%2Fg%2F120l7rzg?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Av. Industrial, 600 &#8211; Centro &#8211; Grand Plaza Shopping<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-a540ca5\" data-id=\"a540ca5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-af0214c\" data-id=\"af0214c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2730e36 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"2730e36\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/super.png\" alt=\"super\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/super1.png\" alt=\"super1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/super2.png\" alt=\"super2\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/super3.png\" alt=\"super3\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12eab7e elementor-widget elementor-widget-heading\" data-id=\"12eab7e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Super Grill Express<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ae5aaf elementor-widget elementor-widget-text-editor\" data-id=\"5ae5aaf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.facebook.com\/supergrillsp\/?locale=pt_BR\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a href=\"https:\/\/www.instagram.com\/supergrillsp.oficial\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a href=\"https:\/\/www.supergrillexpress.com.br\/santoandre.html\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52c493c elementor-widget elementor-widget-text-editor\" data-id=\"52c493c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps?sca_esv=f4dacfe81c780abe&amp;sca_upv=1&amp;rlz=1C1GCEU_pt-BRBR1098BR1098&amp;output=search&amp;q=shopping+abc&amp;source=lnms&amp;entry=mc&amp;utm_campaign=srp-cst&amp;ved=1t:200715&amp;ictx=111\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Av. Pereira Barreto, 42 &#8211; Vl. Gilda\u00a0 &#8211; Shopping ABC<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-6a7ae12\" data-id=\"6a7ae12\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-7fb802c\" data-id=\"7fb802c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cd6565b elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"cd6565b\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/temakeria.png\" alt=\"temakeria\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/temakeria1.png\" alt=\"temakeria1\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00e36e6 elementor-widget elementor-widget-heading\" data-id=\"00e36e6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Temakeria e Cia<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1de4bd3 elementor-widget elementor-widget-text-editor\" data-id=\"1de4bd3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.facebook.com\/temakeria.oficial\/?paipv=0&amp;eav=AfZpPc4usLdEtS_CXwek3VZOhMK6muw8PgGZIktppBCplH9ajIHQVzOe4OfdJ2ggaHQ&amp;_rdr\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c999aa6 elementor-widget elementor-widget-text-editor\" data-id=\"c999aa6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Grand+Plaza+Shopping\/@-23.6487368,-46.5346137,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce4294ff676307:0xd9bb1a8238ff865a!8m2!3d-23.6487368!4d-46.5320388!16s%2Fg%2F120l7rzg?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Av. Industrial, 600 &#8211; Centro &#8211; Grand Plaza Shopping<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-17686a4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"17686a4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9c50622\" data-id=\"9c50622\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-95acd6b elementor-widget elementor-widget-spacer\" data-id=\"95acd6b\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ee27c03 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ee27c03\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-4f69bbd\" data-id=\"4f69bbd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-064b5d6 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"064b5d6\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/tex1.png\" alt=\"tex1\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/tex2.png\" alt=\"tex2\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/tex3.png\" alt=\"tex3\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/03\/tex4.png\" alt=\"tex4\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fbe5e1 elementor-widget elementor-widget-heading\" data-id=\"2fbe5e1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Tex Mex Madrecita<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb54cad elementor-widget elementor-widget-text-editor\" data-id=\"bb54cad\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.facebook.com\/texmadrecita\/about?locale=pt_BR\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.instagram.com\/texmexmadrecita\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/texmexmadrecita.com.br\/texmexmadrecita\/texmexmadrecita?dd=menu\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e886433 elementor-widget elementor-widget-text-editor\" data-id=\"e886433\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Madrecita+Tex-Mex\/@-23.6635319,-46.5309175,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce42882b30c64d:0xe232056fb8fce6bc!8m2!3d-23.6635368!4d-46.5283426!16s%2Fg%2F11b6gs0fqj?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Rua Santo Andr\u00e9, 134 &#8211; Vila Assun\u00e7\u00e3o<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-23f2843\" data-id=\"23f2843\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-edc63bf\" data-id=\"edc63bf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9bc8363 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"9bc8363\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/travessa.png\" alt=\"travessa\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/travessa2-768x432.png\" alt=\"travessa2\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b954146 elementor-widget elementor-widget-heading\" data-id=\"b954146\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Travessa 03 Gastronomia<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f58fa9 elementor-widget elementor-widget-text-editor\" data-id=\"7f58fa9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.facebook.com\/Travessa03\/?locale=pt_BR\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/travessa03.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/travessa03.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90ad173 elementor-widget elementor-widget-text-editor\" data-id=\"90ad173\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps?sca_esv=f807be754d1cd3a2&amp;sca_upv=1&amp;rlz=1C1GCEU_pt-BRBR1098BR1098&amp;output=search&amp;q=Av.+da+Saudade,+184+-+Vila+Assun%C3%A7%C3%A3o&amp;source=lnms&amp;entry=mc&amp;ved=1t:200715&amp;ictx=111\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Av. da Saudade, 184 &#8211; Vila Assun\u00e7\u00e3o<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-acf5c3c\" data-id=\"acf5c3c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-bfc2507\" data-id=\"bfc2507\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cb1e090 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"cb1e090\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/via3-768x432.png\" alt=\"via3\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/via.png\" alt=\"via\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d190b5a elementor-widget elementor-widget-heading\" data-id=\"d190b5a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Via Fico Ristorante<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70768bc elementor-widget elementor-widget-text-editor\" data-id=\"70768bc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5057ef3 elementor-widget elementor-widget-text-editor\" data-id=\"5057ef3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps?sca_esv=76a168b65a348735&amp;rlz=1C1GCEU_pt-BRBR1098BR1098&amp;output=search&amp;q=Rua+das+figueiras+832,+Jardim&amp;source=lnms&amp;entry=mc&amp;ved=1t:200715&amp;ictx=111\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Rua das figueiras 832, Jardim<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-93b36ea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"93b36ea\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a5ecd27\" data-id=\"a5ecd27\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32cac40 elementor-widget elementor-widget-spacer\" data-id=\"32cac40\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e46b044 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e46b044\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-d1a43e9\" data-id=\"d1a43e9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3abef45 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"3abef45\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/11\/c028863a-3765-42b3-adc8-3240a8f3be5c.jpg\" alt=\"c028863a-3765-42b3-adc8-3240a8f3be5c\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/11\/41c3c016-d982-4803-90bd-9ca6eb989946-768x432.jpg\" alt=\"41c3c016-d982-4803-90bd-9ca6eb989946\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2025\/11\/7ab4d6ef-7a13-4657-84a8-e2cbbbcff50b-768x432.jpg\" alt=\"7ab4d6ef-7a13-4657-84a8-e2cbbbcff50b\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c61c0d elementor-widget elementor-widget-heading\" data-id=\"1c61c0d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Villa Portugal Bar e Restaurante <\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf648e4 elementor-widget elementor-widget-text-editor\" data-id=\"cf648e4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.facebook.com\/VillaPortugalBar?rdid=By8PcCfcZknAt55D&amp;share_url=https%3A%2F%2Fwww.facebook.com%2Fshare%2F1CC3wRiJGN%2F#\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.instagram.com\/villaportugalbarrestaurante\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ddff42a elementor-widget elementor-widget-text-editor\" data-id=\"ddff42a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/maps.app.goo.gl\/S6KWuseoeRq3JXBb8\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Travessa Portugal, 25 &#8211; Jardim Bela Vista<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-7001a62\" data-id=\"7001a62\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-1208da1\" data-id=\"1208da1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0518cf7 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"0518cf7\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/viva4-1.png\" alt=\"viva4\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/viva3-1.png\" alt=\"viva3\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/viva2-1.png\" alt=\"viva2\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/viva1-1-768x432.png\" alt=\"viva1\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-782054e elementor-widget elementor-widget-heading\" data-id=\"782054e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Viva Churrascaria\n<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7748e29 elementor-widget elementor-widget-text-editor\" data-id=\"7748e29\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.facebook.com\/churrascariaviva\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.instagram.com\/churrascariavivaoficial\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/api.whatsapp.com\/send\/?phone=551143162724&amp;text&amp;type=phone_number&amp;app_absent=0\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-561bf23 elementor-widget elementor-widget-text-editor\" data-id=\"561bf23\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/R+Orat%C3%B3rio,+32+-+Bang%C3%BA,+Santo+Andr%C3%A9+-+SP,+09280-550\/@-23.647081,-46.5277319,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce4299c2f387c9:0xe35635da3365e1a9!8m2!3d-23.647081!4d-46.525157!16s%2Fg%2F11c27lzxw6?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Rua Orat\u00f3rio, 32 &#8211; Bang\u00fa, Santo Andr\u00e9\u00a0<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-981b64b\" data-id=\"981b64b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-e3a2243\" data-id=\"e3a2243\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ab3ed3 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"7ab3ed3\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/05\/cam-1.png\" alt=\"cam\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/05\/cam2.png\" alt=\"cam2\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/05\/cam4.png\" alt=\"cam4\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/05\/cam5-768x432.png\" alt=\"cam5\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1cb9567 elementor-widget elementor-widget-heading\" data-id=\"1cb9567\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Vivenda do Camar\u00e3o\n<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef91f48 elementor-widget elementor-widget-text-editor\" data-id=\"ef91f48\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.facebook.com\/vivendacamarao\"><img loading=\"lazy\" class=\"alignnone wp-image-17614\" style=\"font-size: 16px;\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-facebook-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.instagram.com\/vivendadocamaraooficial\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17615\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-instagram-48.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.vivendadocamarao.com.br\/\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-facfc26 elementor-widget elementor-widget-text-editor\" data-id=\"facfc26\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps?sca_esv=f4dacfe81c780abe&amp;sca_upv=1&amp;rlz=1C1GCEU_pt-BRBR1098BR1098&amp;output=search&amp;q=shopping+abc&amp;source=lnms&amp;entry=mc&amp;utm_campaign=srp-cst&amp;ved=1t:200715&amp;ictx=111\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Av. Pereira Barreto, 42 &#8211; Vl. Gilda\u00a0 &#8211; Shopping ABC<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b798cef elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b798cef\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ec75d53\" data-id=\"ec75d53\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-092f31e elementor-widget elementor-widget-spacer\" data-id=\"092f31e\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-83b0d97 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"83b0d97\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-5506016\" data-id=\"5506016\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8f4973d elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"8f4973d\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/pastel.png\" alt=\"pastel\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/04\/pastel1.png\" alt=\"pastel1\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a21b321 elementor-widget elementor-widget-heading\" data-id=\"a21b321\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Vivenda do Pastel<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-803a643 elementor-widget elementor-widget-text-editor\" data-id=\"803a643\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h5 class=\"entry-title\" style=\"text-align: center;\"><a style=\"font-family: Roboto, sans-serif; font-size: 18px; font-weight: bold;\" href=\"https:\/\/www.ifood.com.br\/delivery\/santo-andre-sp\/vivenda-do-pastel---grand-plaza-shopping-campestre\/6ce9fe46-8c21-46a6-9409-9f0bf54119ab\/?utm_source=MapPlaceAction\"><img loading=\"lazy\" class=\"alignnone wp-image-17616\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2023\/08\/icons8-site-48.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/h5>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5eb9f9 elementor-widget elementor-widget-text-editor\" data-id=\"e5eb9f9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/www.google.com\/maps\/place\/Grand+Plaza+Shopping\/@-23.6487368,-46.5346137,17z\/data=!3m1!4b1!4m6!3m5!1s0x94ce4294ff676307:0xd9bb1a8238ff865a!8m2!3d-23.6487368!4d-46.5320388!16s%2Fg%2F120l7rzg?entry=ttu\"><img loading=\"lazy\" class=\"alignnone wp-image-19386\" src=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2-150x150.png 150w, https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-content\/uploads\/2024\/02\/map_854901-2.png 256w\" sizes=\"(max-width: 38px) 100vw, 38px\" \/><\/a><br \/><strong>Av. Industrial, 600 &#8211; Centro &#8211; Grand Plaza Shopping<\/strong><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-06788d4\" data-id=\"06788d4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-7dd956c\" data-id=\"7dd956c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-670d919\" data-id=\"670d919\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-edd52bc\" data-id=\"edd52bc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cea55c2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cea55c2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dff6980\" data-id=\"dff6980\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8947b67 elementor-widget elementor-widget-spacer\" data-id=\"8947b67\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9afc44c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9afc44c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-f89c0c3\" data-id=\"f89c0c3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-db97fc8\" data-id=\"db97fc8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-552b2c9\" data-id=\"552b2c9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-861c50b\" data-id=\"861c50b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-1721d3c\" data-id=\"1721d3c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-84de718 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"84de718\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-acfab1b\" data-id=\"acfab1b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0ff02f1 elementor-widget elementor-widget-spacer\" data-id=\"0ff02f1\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>RESTAURANTES Anterior Pr\u00f3ximo Antisa &#038; Roketa Av. Pereira Barreto, n\u00b0 1395 \u2013 Para\u00edso, Santo Andr\u00e9 \u2013 SP, 09190-610 \u2013 loja 03, T\u00e9rreo\u00a0 Anterior Pr\u00f3ximo Arccos<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"spay_email":""},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"himalayas-featured-post":false,"himalayas-portfolio-image":false,"himalayas-featured-image":false,"himalayas-services":false},"uagb_author_info":{"display_name":"Admin","author_link":"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/author\/admtur\/"},"uagb_comment_info":0,"uagb_excerpt":"RESTAURANTES Anterior Pr\u00f3ximo Antisa &#038; Roketa Av. Pereira Barreto, n\u00b0 1395 \u2013 Para\u00edso, Santo Andr\u00e9 \u2013 SP, 09190-610 \u2013 loja 03, T\u00e9rreo\u00a0 Anterior Pr\u00f3ximo Arccos","_links":{"self":[{"href":"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-json\/wp\/v2\/pages\/15204"}],"collection":[{"href":"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-json\/wp\/v2\/comments?post=15204"}],"version-history":[{"count":540,"href":"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-json\/wp\/v2\/pages\/15204\/revisions"}],"predecessor-version":[{"id":32368,"href":"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-json\/wp\/v2\/pages\/15204\/revisions\/32368"}],"wp:attachment":[{"href":"https:\/\/www3.santoandre.sp.gov.br\/turismosantoandre\/wp-json\/wp\/v2\/media?parent=15204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}